{"id":3999,"date":"2024-07-25T13:39:26","date_gmt":"2024-07-25T11:39:26","guid":{"rendered":"https:\/\/ibq.onlinevalles.club\/?page_id=3999"},"modified":"2024-12-10T10:11:28","modified_gmt":"2024-12-10T09:11:28","slug":"id","status":"publish","type":"page","link":"https:\/\/ibq.onlinevalles.club\/en\/id\/","title":{"rendered":"R&amp;D"},"content":{"rendered":"<style>.kb-row-layout-id3999_208233-8a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_208233-8a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_208233-8a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(30% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)));}.kb-row-layout-id3999_208233-8a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_208233-8a > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_208233-8a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 3fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_208233-8a > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_208233-8a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_208233-8a alignnone wp-block-kadence-rowlayout\" id=\"procesos\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-wide kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_c6a541-a1 > .kt-inside-inner-col,.kadence-column3999_c6a541-a1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_c6a541-a1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_c6a541-a1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_c6a541-a1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_c6a541-a1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_c6a541-a1{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_c6a541-a1 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_c6a541-a1 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_c6a541-a1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_85df7d-9e > .kt-inside-inner-col,.kadence-column3999_85df7d-9e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_85df7d-9e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_85df7d-9e > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_85df7d-9e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_85df7d-9e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_85df7d-9e{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_85df7d-9e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_85df7d-9e > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_85df7d-9e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3999_e26800-17, .wp-block-kadence-advancedheading.kt-adv-heading3999_e26800-17[data-kb-block=\"kb-adv-heading3999_e26800-17\"]{font-style:normal;font-family:var( --global-heading-font-family, inherit );text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3999_e26800-17 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_e26800-17[data-kb-block=\"kb-adv-heading3999_e26800-17\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h1 class=\"kt-adv-heading3999_e26800-17 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_e26800-17\"><strong>Fabricado para la seguridad, dise\u00f1ado para la excelencia<\/strong><\/h1>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_7c2332-83 > .kt-inside-inner-col,.kadence-column3999_7c2332-83 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_7c2332-83 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_7c2332-83 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_7c2332-83 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_7c2332-83 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_7c2332-83{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_7c2332-83 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_7c2332-83 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_7c2332-83\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3999_4b7876-26 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_4b7876-26 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_4b7876-26 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:18px;padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)));}.kb-row-layout-id3999_4b7876-26{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kb-row-layout-id3999_4b7876-26 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_4b7876-26 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_4b7876-26 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id3999_4b7876-26{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-row-layout-id3999_4b7876-26 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_4b7876-26 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_4b7876-26{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_4b7876-26 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-half kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_56507f-32 > .kt-inside-inner-col,.kadence-column3999_56507f-32 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_56507f-32 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_56507f-32 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_56507f-32 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_56507f-32 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_56507f-32{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_56507f-32 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_56507f-32 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_56507f-32\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_f5c1aa-62 > .kt-inside-inner-col,.kadence-column3999_f5c1aa-62 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_f5c1aa-62 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_f5c1aa-62 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_f5c1aa-62 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_f5c1aa-62 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_f5c1aa-62{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_f5c1aa-62 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_f5c1aa-62 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_f5c1aa-62\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\">En IBQ Textiles tenemos la capacidad \u00fanica de controlar todo el proceso de fabricaci\u00f3n, desde la selecci\u00f3n del hilo y el tejido hasta la aplicaci\u00f3n de acabados industriales avanzados. Este enfoque totalmente integrado nos permite innovar en cada fase de la producci\u00f3n, aprovechando nuestras propias instalaciones de urdido, tejido, te\u00f1ido y acabado para perfeccionar y mejorar cada paso. Al empezar a innovar desde el n\u00facleo, nos aseguramos de que cada proceso a\u00f1ada valor y eleve el producto final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro compromiso con la investigaci\u00f3n y el desarrollo nos permite ampliar constantemente los l\u00edmites de la innovaci\u00f3n textil. Con d\u00e9cadas de experiencia t\u00e9cnica, una curiosidad incansable y procesos de vanguardia, creamos soluciones innovadoras dise\u00f1adas para superar incluso los retos m\u00e1s exigentes. En IBQ, combinamos alta calidad con avances pioneros para crear un valor excepcional para nuestros clientes, garantizando que permanecemos a la vanguardia de una industria en constante evoluci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<style>.kadence-video-popup3999_b4ac91-00 .kadence-video-popup-wrap .kadence-video-overlay{opacity:0.3;;mix-blend-mode:none;;background:#000000;;}.kadence-video-popup3999_b4ac91-00 .kadence-video-popup-wrap:hover .kadence-video-overlay{opacity:0.5;;}.kadence-video-popup3999_b4ac91-00 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}.kadence-video-popup3999_b4ac91-00 .kadence-video-popup-wrap .kt-video-svg-icon{color:#ffffff;}.kadence-video-popup3999_b4ac91-00 .kadence-video-popup-wrap .kt-video-svg-icon > svg{stroke-width:2;}.glightbox-kadence-dark.kadence-popup-3999_b4ac91-00 .goverlay{background:#000000;opacity:0.8;}.glightbox-container.kadence-popup-3999_b4ac91-00 .gclose path, .glightbox-container.kadence-popup-3999_b4ac91-00 .gnext path, .glightbox-container.kadence-popup-3999_b4ac91-00 .gprev path{fill:#ffffff;}.glightbox-container.kadence-popup-3999_b4ac91-00 .gslide-video, .glightbox-container.kadence-popup-3999_b4ac91-00 .gvideo-local{max-width:900px !important;}@media all and (max-width: 1024px){.kadence-video-popup3999_b4ac91-00 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}}@media all and (max-width: 767px){.kadence-video-popup3999_b4ac91-00 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-videopopup kadence-video-popup3999_b4ac91-00\"><div class=\"kadence-video-popup-wrap kadence-video-noshadow\"><div class=\"kadence-video-intrinsic \"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/11\/NubeTag_ENG-1.png\" alt=\"\" width=\"1920\" height=\"1095\" class=\"kadence-video-poster wp-image-6474\" srcset=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/11\/NubeTag_ENG-1.png 1920w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/11\/NubeTag_ENG-1-300x171.png 300w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/11\/NubeTag_ENG-1-1024x584.png 1024w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/11\/NubeTag_ENG-1-768x438.png 768w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/11\/NubeTag_ENG-1-1536x876.png 1536w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/11\/NubeTag_ENG-1-18x10.png 18w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/11\/NubeTag_ENG-1-1200x684.png 1200w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"kadence-video-overlay\"><\/div><a class=\"kadence-video-popup-link kadence-video-type-external\" href=\"https:\/\/youtu.be\/KKTq8nTSLqE\" role=\"button\" data-popup-class=\"kadence-popup-3999_b4ac91-00\" data-effect=\"none\" data-popup-id=\"kadence-local-video-3999_b4ac91-00\" data-popup-auto=\"true\" data-youtube-cookies=\"true\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_play kt-video-svg-icon kt-video-svg-icon-style-default kt-video-svg-icon-fas play kt-video-play-animation-none kt-video-svg-icon-size-auto\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Play<\/title><path d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"\/><\/svg><\/span><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_3f492f-41 > .kt-inside-inner-col,.kadence-column3999_3f492f-41 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_3f492f-41 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_3f492f-41 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_3f492f-41 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_3f492f-41 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_3f492f-41{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_3f492f-41 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_3f492f-41 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_3f492f-41\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3999_278e98-49 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_278e98-49 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_278e98-49 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)));}.kb-row-layout-id3999_278e98-49 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_278e98-49 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_278e98-49 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 3fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_278e98-49 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_278e98-49 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_278e98-49 alignnone wp-block-kadence-rowlayout\" id=\"procesos\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-wide kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_50ca34-67 > .kt-inside-inner-col,.kadence-column3999_50ca34-67 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_50ca34-67 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_50ca34-67 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_50ca34-67 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_50ca34-67 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_50ca34-67{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_50ca34-67 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_50ca34-67 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_50ca34-67\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_89a1c9-7c > .kt-inside-inner-col,.kadence-column3999_89a1c9-7c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_89a1c9-7c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_89a1c9-7c > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_89a1c9-7c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_89a1c9-7c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_89a1c9-7c{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_89a1c9-7c > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_89a1c9-7c > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_89a1c9-7c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3999_7b98ab-11, .wp-block-kadence-advancedheading.kt-adv-heading3999_7b98ab-11[data-kb-block=\"kb-adv-heading3999_7b98ab-11\"]{margin-bottom:0px;font-style:normal;font-family:var( --global-heading-font-family, inherit );text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3999_7b98ab-11 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_7b98ab-11[data-kb-block=\"kb-adv-heading3999_7b98ab-11\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h1 class=\"kt-adv-heading3999_7b98ab-11 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_7b98ab-11\"><strong>Controlamos todo el proceso de fabricaci\u00f3n, lo que nos proporciona una cadena de valor vertical completa que nos distingue en el sector de los tejidos t\u00e9cnicos.<\/strong><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_08f6a9-8d > .kt-inside-inner-col,.kadence-column3999_08f6a9-8d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_08f6a9-8d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_08f6a9-8d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_08f6a9-8d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_08f6a9-8d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_08f6a9-8d{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_08f6a9-8d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_08f6a9-8d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_08f6a9-8d\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3999_0a7800-6f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_0a7800-6f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_0a7800-6f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)));}.kb-row-layout-id3999_0a7800-6f{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kb-row-layout-id3999_0a7800-6f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_0a7800-6f > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_0a7800-6f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 6fr) minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id3999_0a7800-6f{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-row-layout-id3999_0a7800-6f > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_0a7800-6f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_0a7800-6f{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_0a7800-6f alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-exwide kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_42f14c-59 > .kt-inside-inner-col,.kadence-column3999_42f14c-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_42f14c-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_42f14c-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_42f14c-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_42f14c-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_42f14c-59{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_42f14c-59 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_42f14c-59 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_42f14c-59\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_3b7c48-14 > .kt-inside-inner-col,.kadence-column3999_3b7c48-14 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_3b7c48-14 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_3b7c48-14 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_3b7c48-14 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_3b7c48-14 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_3b7c48-14{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_3b7c48-14 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_3b7c48-14 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_3b7c48-14\"><div class=\"kt-inside-inner-col\">\n<a href=\"#\" data-toggle=\"collapse\" data-target=\"design\" class=\"collapse-title\">La innovaci\u00f3n comienza por la perspicacia y el prop\u00f3sito<\/a>\n\n\n<style>.kb-row-layout-id3999_5da413-c6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_5da413-c6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_5da413-c6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_5da413-c6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_5da413-c6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_5da413-c6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_5da413-c6 alignnone collapse-content wp-block-kadence-rowlayout\" id=\"design\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3999_55a1da-ca > .kt-inside-inner-col{padding-top:30px;}.kadence-column3999_55a1da-ca > .kt-inside-inner-col,.kadence-column3999_55a1da-ca > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_55a1da-ca > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_55a1da-ca > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_55a1da-ca > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_55a1da-ca > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_55a1da-ca{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_55a1da-ca > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_55a1da-ca > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_55a1da-ca\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\">En IBQ Textiles, tenemos claro que nuestra misi\u00f3n se basa en mejorar nuestros tejidos para aportar la mejor protecci\u00f3n con textiles avanzados y sostenibles para condiciones extremas. Conseguirlo requiere un compromiso de mejora, innovaci\u00f3n y desarrollo continuos. Estos avances pueden provenir de procesos internos de la f\u00e1brica, nuevas fuentes de materias primas, maquinaria mejorada o ideas recogidas de las tendencias del mercado y las peticiones de los clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00e9xito de la innovaci\u00f3n comienza con un profundo conocimiento del uso final del producto, las necesidades espec\u00edficas, las condiciones de funcionamiento y los requisitos funcionales. Antes de embarcarnos en cualquier desarrollo, nos tomamos el tiempo necesario para definir claramente la aplicaci\u00f3n prevista del refuerzo. As\u00ed nos aseguramos de que nuestros esfuerzos sean estrat\u00e9gicos y tengan impacto, impulsando avances significativos que beneficien a nuestros clientes y a las industrias a las que servimos.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3999_f75f93-44 > .kt-inside-inner-col,.kadence-column3999_f75f93-44 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_f75f93-44 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_f75f93-44 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_f75f93-44 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_f75f93-44 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_f75f93-44{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_f75f93-44 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_f75f93-44 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_f75f93-44\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3999_6c4816-e1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_6c4816-e1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_6c4816-e1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)));}.kb-row-layout-id3999_6c4816-e1{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kb-row-layout-id3999_6c4816-e1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_6c4816-e1 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_6c4816-e1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 6fr) minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id3999_6c4816-e1{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-row-layout-id3999_6c4816-e1 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_6c4816-e1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_6c4816-e1{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_6c4816-e1 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-exwide kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_98b1ff-01 > .kt-inside-inner-col,.kadence-column3999_98b1ff-01 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_98b1ff-01 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_98b1ff-01 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_98b1ff-01 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_98b1ff-01 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_98b1ff-01{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_98b1ff-01 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_98b1ff-01 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_98b1ff-01\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_bbb0da-8a > .kt-inside-inner-col,.kadence-column3999_bbb0da-8a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_bbb0da-8a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_bbb0da-8a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_bbb0da-8a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_bbb0da-8a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_bbb0da-8a{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_bbb0da-8a > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_bbb0da-8a > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_bbb0da-8a\"><div class=\"kt-inside-inner-col\">\n<a href=\"#\" data-toggle=\"collapse\" data-target=\"capacidades\" class=\"collapse-title\">Selecci\u00f3n de materias primas e hilos<\/a>\n\n\n<style>.kb-row-layout-id3999_bacbce-03 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_bacbce-03 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_bacbce-03 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_bacbce-03 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_bacbce-03 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_bacbce-03 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_bacbce-03 alignnone collapse-content wp-block-kadence-rowlayout\" id=\"capacidades\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3999_6b2acc-f9 > .kt-inside-inner-col{padding-top:30px;}.kadence-column3999_6b2acc-f9 > .kt-inside-inner-col,.kadence-column3999_6b2acc-f9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_6b2acc-f9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_6b2acc-f9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_6b2acc-f9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_6b2acc-f9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_6b2acc-f9{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_6b2acc-f9 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_6b2acc-f9 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_6b2acc-f9\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\">Con d\u00e9cadas de experiencia, el equipo de IBQ Textiles posee profundos conocimientos en materias primas y tipos de hilo, lo que nos permite desarrollar y perfeccionar tejidos que ofrecen un rendimiento excepcional en cualquier entorno y para cualquier requisito. Seleccionamos \u00fanicamente materiales que cumplen los m\u00e1s altos est\u00e1ndares de calidad y sostenibilidad, forjando alianzas con algunas de las marcas m\u00e1s renombradas de la industria de fabricaci\u00f3n de fibras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En colaboraci\u00f3n con innovadores como Dyneema<sup>\u00ae<\/sup>, Cordura<sup>\u00ae<\/sup>, Kevlar<sup>\u00ae<\/sup>, COOLMAX<sup>\u00ae<\/sup>, ECONYL<sup>\u00ae<\/sup>, SENSIL<sup>\u00ae<\/sup> Breeze, SENSIL<sup>\u00ae<\/sup> Heat y LYCRA<sup>\u00ae<\/sup>, incorporamos sus avanzadas fibras a nuestros tejidos. Estas alianzas nos permiten ofrecer una cartera de tejidos reconocidos por su durabilidad, rendimiento, protecci\u00f3n y confort.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al colaborar estrechamente con fabricantes de hilos avanzados, garantizamos el acceso a hilos de la m\u00e1xima calidad y fomentamos la innovaci\u00f3n a nivel de hilo. Este enfoque nos permite crear hilos \u00fanicos y especializados para satisfacer necesidades espec\u00edficas de rendimiento o para ampliar los l\u00edmites de lo que es posible en tecnolog\u00eda textil.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3999_48a97f-7d > .kt-inside-inner-col,.kadence-column3999_48a97f-7d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_48a97f-7d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_48a97f-7d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_48a97f-7d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_48a97f-7d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_48a97f-7d{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_48a97f-7d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_48a97f-7d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_48a97f-7d\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3999_7da233-01 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_7da233-01 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_7da233-01 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)));}.kb-row-layout-id3999_7da233-01{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kb-row-layout-id3999_7da233-01 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_7da233-01 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_7da233-01 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 6fr) minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id3999_7da233-01{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-row-layout-id3999_7da233-01 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_7da233-01 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_7da233-01{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_7da233-01 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-exwide kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_a7a54e-a3 > .kt-inside-inner-col,.kadence-column3999_a7a54e-a3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_a7a54e-a3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_a7a54e-a3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_a7a54e-a3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_a7a54e-a3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_a7a54e-a3{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_a7a54e-a3 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_a7a54e-a3 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_a7a54e-a3\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_60af3d-45 > .kt-inside-inner-col,.kadence-column3999_60af3d-45 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_60af3d-45 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_60af3d-45 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_60af3d-45 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_60af3d-45 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_60af3d-45{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_60af3d-45 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_60af3d-45 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_60af3d-45\"><div class=\"kt-inside-inner-col\">\n<a href=\"#\" data-toggle=\"collapse\" data-target=\"materiales\" class=\"collapse-title\">Tejedur\u00eda de precisi\u00f3n para necesidades futuras<\/a>\n\n\n<style>.kb-row-layout-id3999_4e81e8-40 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_4e81e8-40 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_4e81e8-40 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_4e81e8-40 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_4e81e8-40 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_4e81e8-40 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_4e81e8-40 alignnone collapse-content wp-block-kadence-rowlayout\" id=\"materiales\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3999_fa9ad0-14 > .kt-inside-inner-col{padding-top:30px;}.kadence-column3999_fa9ad0-14 > .kt-inside-inner-col,.kadence-column3999_fa9ad0-14 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_fa9ad0-14 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_fa9ad0-14 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_fa9ad0-14 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_fa9ad0-14 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_fa9ad0-14{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_fa9ad0-14 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_fa9ad0-14 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_fa9ad0-14\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\">IBQ Textiles tiene el control total sobre la fase de tejedur\u00eda de nuestra cadena de procesos. Desde la cuidadosa selecci\u00f3n y compra de hilos de alta calidad hasta la supervisi\u00f3n exhaustiva de cada paso del proceso de producci\u00f3n, garantizamos precisi\u00f3n y flexibilidad en todos los niveles. Nuestras capacidades internas incluyen la preparaci\u00f3n del urdido y la tejedur\u00eda, lo que nos permite responder din\u00e1micamente a las necesidades espec\u00edficas de cada proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestras instalaciones de tejedur\u00eda, que ocupan una impresionante superficie de 6.000 m\u00b2, est\u00e1n equipadas con 36 telares de \u00faltima generaci\u00f3n. La mayor\u00eda de estos telares son adaptables a configuraciones de doble plegador, lo que nos permite crear tejidos complejos de varias capas adaptados a aplicaciones de alto rendimiento. Adem\u00e1s, las instalaciones cuentan con sistemas de tejedur\u00eda con pinzas negativas y positivas, lo que nos permite trabajar con hilos avanzados y dif\u00edciles, como los utilizados en tejidos t\u00e9cnicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 2012, nuestras operaciones de tejedur\u00eda han sido la piedra angular de nuestro compromiso con la innovaci\u00f3n en textiles t\u00e9cnicos. Al mantener el control directo sobre esta etapa cr\u00edtica, capacitamos a nuestro equipo para desarrollar soluciones personalizadas que satisfagan las cambiantes demandas del mercado, al tiempo que garantizamos una calidad y fiabilidad constantes.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3999_1498f8-d7 > .kt-inside-inner-col,.kadence-column3999_1498f8-d7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_1498f8-d7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_1498f8-d7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_1498f8-d7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_1498f8-d7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_1498f8-d7{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_1498f8-d7 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_1498f8-d7 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_1498f8-d7\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3999_45f194-42 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_45f194-42 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_45f194-42 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)));}.kb-row-layout-id3999_45f194-42{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kb-row-layout-id3999_45f194-42 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_45f194-42 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_45f194-42 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 6fr) minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id3999_45f194-42{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-row-layout-id3999_45f194-42 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_45f194-42 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_45f194-42{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_45f194-42 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-exwide kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_3c66cb-5f > .kt-inside-inner-col,.kadence-column3999_3c66cb-5f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_3c66cb-5f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_3c66cb-5f > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_3c66cb-5f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_3c66cb-5f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_3c66cb-5f{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_3c66cb-5f > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_3c66cb-5f > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_3c66cb-5f\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_32359c-a4 > .kt-inside-inner-col,.kadence-column3999_32359c-a4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_32359c-a4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_32359c-a4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_32359c-a4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_32359c-a4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_32359c-a4{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_32359c-a4 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_32359c-a4 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_32359c-a4\"><div class=\"kt-inside-inner-col\">\n<a href=\"#\" data-toggle=\"collapse\" data-target=\"nucleo\" class=\"collapse-title\">Acabados de calidad para aplicaciones de alto rendimiento<\/a>\n\n\n<style>.kb-row-layout-id3999_df2056-01 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_df2056-01 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_df2056-01 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_df2056-01 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_df2056-01 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_df2056-01 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_df2056-01 alignnone collapse-content wp-block-kadence-rowlayout\" id=\"nucleo\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3999_6d158f-31 > .kt-inside-inner-col{padding-top:30px;}.kadence-column3999_6d158f-31 > .kt-inside-inner-col,.kadence-column3999_6d158f-31 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_6d158f-31 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_6d158f-31 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_6d158f-31 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_6d158f-31 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_6d158f-31{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_6d158f-31 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_6d158f-31 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_6d158f-31\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\">En IBQ, nuestras propias instalaciones de acabado son el punto de encuentro entre la innovaci\u00f3n y la sostenibilidad. Con m\u00e1s de 60 a\u00f1os de experiencia como l\u00edder en la industria textil espa\u00f1ola, evolucionamos continuamente nuestros procesos para minimizar el consumo de agua, gas y electricidad. Nuestro avanzado proceso de tintura reduce el consumo de agua hasta en un 30%*, estableciendo puntos de referencia en el sector en cuanto a ecoeficiencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Somos pioneros en la adopci\u00f3n de productos sin PFAS desde hace una d\u00e9cada, muy por delante de las normas del sector. Esta iniciativa forma parte de nuestro compromiso m\u00e1s amplio con la sostenibilidad, que tambi\u00e9n incluye el desarrollo de una lavadora \u00fanica. Creada en colaboraci\u00f3n con destacados equipos de ingenier\u00eda, esta m\u00e1quina reduce significativamente el consumo de agua y fue desarrollada exclusivamente para nuestro uso tras m\u00e1s de dos a\u00f1os de intensa investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En IBQ Textiles, ofrecemos una amplia gama de acabados, incluyendo repelencia al agua, resistencia a las manchas y al fuego, cepillado, laminaci\u00f3n y membranas. Nuestras capacidades internas, combinadas con asociaciones con empresas de acabado locales, nos permiten ofrecer opciones de acabado a medida y expansivas para satisfacer las necesidades espec\u00edficas de los clientes.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\" style=\"font-size:10px\">*Consumo por metro de tejido producido.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3999_5d8c42-ea > .kt-inside-inner-col,.kadence-column3999_5d8c42-ea > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_5d8c42-ea > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_5d8c42-ea > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_5d8c42-ea > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_5d8c42-ea > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_5d8c42-ea{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_5d8c42-ea > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_5d8c42-ea > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_5d8c42-ea\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3999_80fe5b-df > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_80fe5b-df > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_80fe5b-df > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)));}.kb-row-layout-id3999_80fe5b-df{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kb-row-layout-id3999_80fe5b-df > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_80fe5b-df > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_80fe5b-df > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 6fr) minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id3999_80fe5b-df{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-row-layout-id3999_80fe5b-df > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_80fe5b-df > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_80fe5b-df{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_80fe5b-df alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-exwide kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_e80cb3-7d > .kt-inside-inner-col,.kadence-column3999_e80cb3-7d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_e80cb3-7d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_e80cb3-7d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_e80cb3-7d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_e80cb3-7d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_e80cb3-7d{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_e80cb3-7d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_e80cb3-7d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_e80cb3-7d\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_ede34a-57 > .kt-inside-inner-col,.kadence-column3999_ede34a-57 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_ede34a-57 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_ede34a-57 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_ede34a-57 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_ede34a-57 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_ede34a-57{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_ede34a-57 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_ede34a-57 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_ede34a-57\"><div class=\"kt-inside-inner-col\">\n<a href=\"#\" data-toggle=\"collapse\" data-target=\"acabado\" class=\"collapse-title\">Ensayos y controles de calidad avanzados<\/a>\n\n\n<style>.kb-row-layout-id3999_92b248-ab > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_92b248-ab > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_92b248-ab > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_92b248-ab > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_92b248-ab > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_92b248-ab > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_92b248-ab alignnone collapse-content wp-block-kadence-rowlayout\" id=\"acabado\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3999_204653-65 > .kt-inside-inner-col{padding-top:30px;}.kadence-column3999_204653-65 > .kt-inside-inner-col,.kadence-column3999_204653-65 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_204653-65 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_204653-65 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_204653-65 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_204653-65 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_204653-65{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_204653-65 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_204653-65 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_204653-65\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\">En IBQ Textiles, la innovaci\u00f3n y la calidad est\u00e1n perfectamente entrelazadas. Nuestro compromiso con el avance de los tejidos t\u00e9cnicos se demuestra a trav\u00e9s de nuestros dos laboratorios especializados: un laboratorio h\u00famedo dedicado al desarrollo y ensayo de acabados qu\u00edmicos y colorantes, y un laboratorio f\u00edsico centrado en rigurosos controles de calidad y an\u00e1lisis de tejidos. Esta configuraci\u00f3n nos permite destacar en la creaci\u00f3n de textiles de alto rendimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En nuestro laboratorio h\u00famedo, exploramos continuamente tratamientos innovadores y perfeccionamos los procesos de tintura, ampliando los l\u00edmites de la tecnolog\u00eda textil. Este enfoque proactivo garantiza que satisfacemos las necesidades din\u00e1micas de nuestra industria con precisi\u00f3n e innovaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro laboratorio de calidad f\u00edsica desempe\u00f1a un papel fundamental en el mantenimiento de los m\u00e1s altos niveles de calidad de los tejidos. Equipado con herramientas avanzadas, nuestro cualificado equipo realiza evaluaciones precisas en tres fases cr\u00edticas de la producci\u00f3n de tejidos: crudo, en proceso y producto final. Cada lote se somete a una inspecci\u00f3n al 100% para verificar el color, la anchura, el peso y las imperfecciones, garantizando la coherencia, la fiabilidad y la excelencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para las certificaciones que requieren validaci\u00f3n externa, colaboramos con laboratorios acreditados, reforzando nuestro compromiso con la calidad y el cumplimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En IBQ Textiles, mantenemos valores de rigor, colaboraci\u00f3n e integridad en todas nuestras relaciones, con un claro enfoque en la entrega de valor y calidad excepcionales a nuestros clientes y proveedores.<br><\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3999_ea7e7d-4a > .kt-inside-inner-col,.kadence-column3999_ea7e7d-4a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_ea7e7d-4a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_ea7e7d-4a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_ea7e7d-4a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_ea7e7d-4a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_ea7e7d-4a{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_ea7e7d-4a > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_ea7e7d-4a > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_ea7e7d-4a\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3999_2fb3c4-8d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_2fb3c4-8d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_2fb3c4-8d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)));}.kb-row-layout-id3999_2fb3c4-8d{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kb-row-layout-id3999_2fb3c4-8d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_2fb3c4-8d > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_2fb3c4-8d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 6fr) minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id3999_2fb3c4-8d{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-row-layout-id3999_2fb3c4-8d > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_2fb3c4-8d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_2fb3c4-8d{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_2fb3c4-8d alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-exwide kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_62c705-6e > .kt-inside-inner-col,.kadence-column3999_62c705-6e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_62c705-6e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_62c705-6e > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_62c705-6e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_62c705-6e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_62c705-6e{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_62c705-6e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_62c705-6e > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_62c705-6e\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_50d69d-1c > .kt-inside-inner-col,.kadence-column3999_50d69d-1c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_50d69d-1c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_50d69d-1c > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_50d69d-1c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_50d69d-1c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_50d69d-1c{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_50d69d-1c > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_50d69d-1c > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_50d69d-1c\"><div class=\"kt-inside-inner-col\">\n<a href=\"#\" data-toggle=\"collapse\" data-target=\"calidad\" class=\"collapse-title\">Log\u00edstica de Entrega Eficiente y Confiable<\/a>\n\n\n<style>.kb-row-layout-id3999_7b83d1-b4 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_7b83d1-b4 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_7b83d1-b4 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_7b83d1-b4 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_7b83d1-b4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_7b83d1-b4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_7b83d1-b4 alignnone collapse-content wp-block-kadence-rowlayout\" id=\"calidad\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3999_da528a-11 > .kt-inside-inner-col{padding-top:30px;}.kadence-column3999_da528a-11 > .kt-inside-inner-col,.kadence-column3999_da528a-11 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_da528a-11 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_da528a-11 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_da528a-11 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_da528a-11 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_da528a-11{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_da528a-11 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_da528a-11 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_da528a-11\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\">En IBQ Textiles, entendemos que el tiempo es cr\u00edtico. Por eso, nuestra log\u00edstica de entrega est\u00e1 dise\u00f1ada con eficiencia. Desde el cuidadoso embalaje hasta la perfecta coordinaci\u00f3n log\u00edstica, cada paso de nuestro proceso tiene como objetivo garantizar que su pedido llegue a tiempo y en perfectas condiciones, listo para ser transformado por nuestros clientes en prendas que marcar\u00e1n la diferencia.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3999_c6150c-bc > .kt-inside-inner-col,.kadence-column3999_c6150c-bc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_c6150c-bc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_c6150c-bc > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_c6150c-bc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_c6150c-bc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_c6150c-bc{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_c6150c-bc > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_c6150c-bc > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_c6150c-bc\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3999_505e72-76 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_505e72-76 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_505e72-76 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(20% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)));}.kb-row-layout-id3999_505e72-76{border-bottom:1px solid var(--global-palette7, #EDF2F7);}.kb-row-layout-id3999_505e72-76 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_505e72-76 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_505e72-76 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 6fr) minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id3999_505e72-76{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-row-layout-id3999_505e72-76 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_505e72-76 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_505e72-76{border-bottom:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_505e72-76 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-exwide kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_4d6c7c-cc > .kt-inside-inner-col,.kadence-column3999_4d6c7c-cc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_4d6c7c-cc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_4d6c7c-cc > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_4d6c7c-cc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_4d6c7c-cc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_4d6c7c-cc{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_4d6c7c-cc > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_4d6c7c-cc > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_4d6c7c-cc\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_de3f12-3a > .kt-inside-inner-col,.kadence-column3999_de3f12-3a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_de3f12-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_de3f12-3a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_de3f12-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_de3f12-3a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_de3f12-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_de3f12-3a > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_de3f12-3a > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_de3f12-3a\"><div class=\"kt-inside-inner-col\">\n<a href=\"#\" data-toggle=\"collapse\" data-target=\"entrega\" class=\"collapse-title\">Atenci\u00f3n al cliente que va m\u00e1s all\u00e1<\/a>\n\n\n<style>.kb-row-layout-id3999_9dc942-3a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_9dc942-3a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_9dc942-3a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_9dc942-3a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_9dc942-3a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_9dc942-3a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_9dc942-3a alignnone collapse-content wp-block-kadence-rowlayout\" id=\"entrega\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3999_16e861-8f > .kt-inside-inner-col{padding-top:30px;}.kadence-column3999_16e861-8f > .kt-inside-inner-col,.kadence-column3999_16e861-8f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_16e861-8f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_16e861-8f > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_16e861-8f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_16e861-8f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_16e861-8f{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_16e861-8f > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_16e861-8f > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_16e861-8f\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\">En IBQ Textiles, creemos que un excelente servicio al cliente es tan importante como la entrega de productos excepcionales. Desde el momento en que el cliente se pone en contacto con nosotros hasta mucho despu\u00e9s de que su pedido se haya completado, nuestro dedicado equipo de atenci\u00f3n al cliente est\u00e1 aqu\u00ed para garantizar que su experiencia sea fluida y satisfactoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entendemos el valor del apoyo personalizado, por lo que nuestro equipo est\u00e1 siempre dispuesto a ayudarte con tus preguntas, proporcionarte orientaci\u00f3n y resolver tus dudas. Tanto si necesitas ayuda para seleccionar el tejido adecuado como para hacer el seguimiento de un pedido o discutir detalles t\u00e9cnicos, nos comprometemos a estar a tu lado en todo momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro objetivo es construir relaciones duraderas con nuestros clientes, basadas en la confianza, la fiabilidad y un compromiso compartido con la excelencia. Con IBQ Textiles, no s\u00f3lo est\u00e1s comprando tejidos, te est\u00e1s asociando con un equipo que realmente se preocupa por tu \u00e9xito.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3999_d44f97-8e > .kt-inside-inner-col,.kadence-column3999_d44f97-8e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_d44f97-8e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_d44f97-8e > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_d44f97-8e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_d44f97-8e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_d44f97-8e{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_d44f97-8e > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_d44f97-8e > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_d44f97-8e\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3999_c9fbe1-ad{margin-top:var(--global-kb-spacing-xxl, 5rem);}.kb-row-layout-id3999_c9fbe1-ad > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_c9fbe1-ad > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_c9fbe1-ad > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id3999_c9fbe1-ad > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_c9fbe1-ad > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 3fr) minmax(0, 1fr);}.kb-row-layout-id3999_c9fbe1-ad > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_c9fbe1-ad > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_c9fbe1-ad > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 3fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_c9fbe1-ad > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_c9fbe1-ad > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_c9fbe1-ad alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\" id=\"colaboraciones\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-wide kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_d0df07-7a > .kt-inside-inner-col,.kadence-column3999_d0df07-7a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_d0df07-7a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_d0df07-7a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_d0df07-7a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_d0df07-7a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_d0df07-7a{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_d0df07-7a > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_d0df07-7a > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_d0df07-7a\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_61fd9f-35 > .kt-inside-inner-col,.kadence-column3999_61fd9f-35 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_61fd9f-35 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_61fd9f-35 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_61fd9f-35 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_61fd9f-35 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_61fd9f-35{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_61fd9f-35 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_61fd9f-35 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_61fd9f-35\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3999_a2e261-c7 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_a2e261-c7 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_a2e261-c7 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_a2e261-c7 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_a2e261-c7 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_a2e261-c7 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_a2e261-c7 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3999_04a7d9-ff > .kt-inside-inner-col,.kadence-column3999_04a7d9-ff > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_04a7d9-ff > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_04a7d9-ff > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_04a7d9-ff > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_04a7d9-ff > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_04a7d9-ff{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_04a7d9-ff > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_04a7d9-ff > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_04a7d9-ff\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3999_3e5484-0c, .wp-block-kadence-advancedheading.kt-adv-heading3999_3e5484-0c[data-kb-block=\"kb-adv-heading3999_3e5484-0c\"]{margin-bottom:30px;font-size:24px;font-weight:400;font-style:normal;font-family:EurostileProExtendedBlack, Helvetica, Arial;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading3999_3e5484-0c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_3e5484-0c[data-kb-block=\"kb-adv-heading3999_3e5484-0c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading3999_3e5484-0c ibq-title-red wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_3e5484-0c\">COLABORACIONES<\/h2>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3999_0ed23c-63 > .kt-inside-inner-col,.kadence-column3999_0ed23c-63 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_0ed23c-63 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_0ed23c-63 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_0ed23c-63 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_0ed23c-63 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_0ed23c-63{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_0ed23c-63 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_0ed23c-63 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_0ed23c-63\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3999_5fe275-da > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_5fe275-da > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_5fe275-da > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_5fe275-da > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_5fe275-da > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_5fe275-da > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_5fe275-da alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_34a43f-5f > .kt-inside-inner-col,.kadence-column3999_34a43f-5f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_34a43f-5f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_34a43f-5f > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_34a43f-5f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_34a43f-5f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_34a43f-5f{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_34a43f-5f > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_34a43f-5f > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_34a43f-5f\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3999_2a661b-57 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_2a661b-57 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_2a661b-57 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3999_2a661b-57 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_2a661b-57 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3999_2a661b-57 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}.kt-inside-inner-col {    border-image: none;}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_2a661b-57 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column3999_039780-b1 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3999_039780-b1 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column3999_039780-b1 > .kt-inside-inner-col,.kadence-column3999_039780-b1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_039780-b1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_039780-b1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_039780-b1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_039780-b1 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3999_039780-b1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_039780-b1{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_039780-b1 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_039780-b1 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_039780-b1 partner-box\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image3999_ff1a0f-12:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image3999_ff1a0f-12.kb-image-is-ratio-size, .kb-image3999_ff1a0f-12 .kb-image-is-ratio-size{max-width:500px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_ff1a0f-12.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_ff1a0f-12 .kb-image-is-ratio-size{align-self:unset;}.kb-image3999_ff1a0f-12 figure{max-width:500px;}.kb-image3999_ff1a0f-12 .image-is-svg, .kb-image3999_ff1a0f-12 .image-is-svg img{width:100%;}.kb-image3999_ff1a0f-12 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3999_ff1a0f-12\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"410\" src=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-dyneema-1024x410.png\" alt=\"\" class=\"kb-img wp-image-4844\" srcset=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-dyneema-1024x410.png 1024w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-dyneema-300x120.png 300w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-dyneema-768x307.png 768w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-dyneema.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3999_c41695-86, .wp-block-kadence-advancedheading.kt-adv-heading3999_c41695-86[data-kb-block=\"kb-adv-heading3999_c41695-86\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:24px;font-weight:400;font-style:normal;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;}.wp-block-kadence-advancedheading.kt-adv-heading3999_c41695-86 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_c41695-86[data-kb-block=\"kb-adv-heading3999_c41695-86\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading3999_c41695-86 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_c41695-86\">La fortaleza transformada en fibra<\/h3>\n\n\n<style>#kt-modal3999_70f4db-6e .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette6, #718096);border-color:var(--global-palette6, #718096);border-radius:4px;font-size:12px;line-height:1.2;letter-spacing:2px;border-width:1px 1px 1px 1px;padding:8px 28px 8px 28px;margin:0px 0px 0px 0px;}#kt-modal3999_70f4db-6e .kt-blocks-modal-link:hover, #kt-modal3999_70f4db-6e .kt-blocks-modal-link:focus{color:#ffffff;background:#444444;border-color:#444444;}#kt-modal3999_70f4db-6e .kt-modal-overlay, #kt-target-modal3999_70f4db-6e .kt-modal-overlay, .kb-modal-content3999_70f4db-6e .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal3999_70f4db-6e .kt-modal-overlay, #kt-target-modal3999_70f4db-6e .kt-modal-overlay, .kb-modal-content3999_70f4db-6e .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal3999_70f4db-6e .kt-modal-container, #kt-target-modal3999_70f4db-6e .kt-modal-container, .kb-modal-content3999_70f4db-6e .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal3999_70f4db-6e .kt-modal-container, #kt-target-modal3999_70f4db-6e .kt-modal-container, .kb-modal-content3999_70f4db-6e .kt-modal-container{padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal3999_70f4db-6e .kt-modal-container, #kt-target-modal3999_70f4db-6e .kt-modal-container, .kb-modal-content3999_70f4db-6e .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_70f4db-6e .kt-modal-close svg, #kt-target-modal3999_70f4db-6e .kt-modal-close svg, .kb-modal-content3999_70f4db-6e .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal3999_70f4db-6e .kt-modal-container, #kt-target-modal3999_70f4db-6e .kt-modal-container, .kb-modal-content3999_70f4db-6e .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal3999_70f4db-6e .kt-modal-close svg, #kt-target-modal3999_70f4db-6e .kt-modal-close svg, .kb-modal-content3999_70f4db-6e .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal3999_70f4db-6e .kt-modal-container, #kt-target-modal3999_70f4db-6e .kt-modal-container, .kb-modal-content3999_70f4db-6e .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_70f4db-6e .kt-modal-close svg, #kt-target-modal3999_70f4db-6e .kt-modal-close svg, .kb-modal-content3999_70f4db-6e .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center\" id=\"kt-modal3999_70f4db-6e\"><div id=\"kt-target-modal3999_70f4db-6e\" class=\"kb-modal-content3999_70f4db-6e kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal3999_70f4db-6e-content\" class=\"kt-modal-content\">\n<p class=\"wp-block-paragraph\">Dyneema<sup>\u00ae<\/sup> representa la cima de la innovaci\u00f3n en fibras de polietileno de alto peso molecular, estableciendo el est\u00e1ndar de referencia en resistencia y ligereza. Esta fibra se distingue por su inigualable resistencia al impacto, corte y abrasi\u00f3n, siendo hasta 15 veces m\u00e1s fuerte que el acero. Su composici\u00f3n la hace inmune a agentes qu\u00edmicos, destacando en entornos donde la durabilidad es crucial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En IBQ, nos enorgullecemos de integrar el hilo Dyneema<sup>\u00ae<\/sup> en la fabricaci\u00f3n de tejidos para refuerzos, aprovechando su excepcional fuerza y versatilidad. La superioridad de Dyneema<sup>\u00ae<\/sup> radica en su asombrosa fortaleza y resistencia. Dise\u00f1ada para desafiar los l\u00edmites de la durabilidad, esta fibra ultra resistente se presta para confeccionar tejidos que soportan las condiciones m\u00e1s extremas sin sacrificar la ligereza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es la esencia de la versatilidad, adapt\u00e1ndose a una amplia gama de aplicaciones que van desde la protecci\u00f3n personal hasta el uso en ambientes industriales que requieren la m\u00e1xima resistencia al desgaste, el corte y las tensiones mec\u00e1nicas. Nuestra utilizaci\u00f3n del hilo Dyneema<sup>\u00ae<\/sup> refleja nuestra b\u00fasqueda constante por soluciones que no solo cumplen con los est\u00e1ndares actuales, sino que los elevan, ofreciendo a nuestros clientes una calidad y un rendimiento que llevan la innovaci\u00f3n a la pr\u00e1ctica.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal3999_70f4db-6e\"><span class=\"kt-blocks-modal-link-inner\">DESCUBRIR M\u00c1S<\/span><\/button><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_211049-3e > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3999_211049-3e > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column3999_211049-3e > .kt-inside-inner-col,.kadence-column3999_211049-3e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_211049-3e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_211049-3e > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_211049-3e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_211049-3e > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3999_211049-3e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_211049-3e{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_211049-3e > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_211049-3e > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_211049-3e partner-box\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image3999_3dbf56-63:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image3999_3dbf56-63.kb-image-is-ratio-size, .kb-image3999_3dbf56-63 .kb-image-is-ratio-size{max-width:500px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_3dbf56-63.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_3dbf56-63 .kb-image-is-ratio-size{align-self:unset;}.kb-image3999_3dbf56-63 figure{max-width:500px;}.kb-image3999_3dbf56-63 .image-is-svg, .kb-image3999_3dbf56-63 .image-is-svg img{width:100%;}.kb-image3999_3dbf56-63 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3999_3dbf56-63\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"410\" src=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-cordura-1024x410.png\" alt=\"\" class=\"kb-img wp-image-4845\" srcset=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-cordura-1024x410.png 1024w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-cordura-300x120.png 300w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-cordura-768x307.png 768w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-cordura.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3999_b7e5b2-b8, .wp-block-kadence-advancedheading.kt-adv-heading3999_b7e5b2-b8[data-kb-block=\"kb-adv-heading3999_b7e5b2-b8\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:24px;font-weight:400;font-style:normal;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;}.wp-block-kadence-advancedheading.kt-adv-heading3999_b7e5b2-b8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_b7e5b2-b8[data-kb-block=\"kb-adv-heading3999_b7e5b2-b8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading3999_b7e5b2-b8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_b7e5b2-b8\">Durabilidad definida<\/h3>\n\n\n<style>#kt-modal3999_f4505f-d3 .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette6, #718096);border-color:var(--global-palette6, #718096);border-radius:4px;font-size:12px;line-height:1.2;letter-spacing:2px;border-width:1px 1px 1px 1px;padding:8px 28px 8px 28px;margin:0px 0px 0px 0px;}#kt-modal3999_f4505f-d3 .kt-blocks-modal-link:hover, #kt-modal3999_f4505f-d3 .kt-blocks-modal-link:focus{color:#ffffff;background:#444444;border-color:#444444;}#kt-modal3999_f4505f-d3 .kt-modal-overlay, #kt-target-modal3999_f4505f-d3 .kt-modal-overlay, .kb-modal-content3999_f4505f-d3 .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal3999_f4505f-d3 .kt-modal-overlay, #kt-target-modal3999_f4505f-d3 .kt-modal-overlay, .kb-modal-content3999_f4505f-d3 .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal3999_f4505f-d3 .kt-modal-container, #kt-target-modal3999_f4505f-d3 .kt-modal-container, .kb-modal-content3999_f4505f-d3 .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal3999_f4505f-d3 .kt-modal-container, #kt-target-modal3999_f4505f-d3 .kt-modal-container, .kb-modal-content3999_f4505f-d3 .kt-modal-container{padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal3999_f4505f-d3 .kt-modal-container, #kt-target-modal3999_f4505f-d3 .kt-modal-container, .kb-modal-content3999_f4505f-d3 .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_f4505f-d3 .kt-modal-close svg, #kt-target-modal3999_f4505f-d3 .kt-modal-close svg, .kb-modal-content3999_f4505f-d3 .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal3999_f4505f-d3 .kt-modal-container, #kt-target-modal3999_f4505f-d3 .kt-modal-container, .kb-modal-content3999_f4505f-d3 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal3999_f4505f-d3 .kt-modal-close svg, #kt-target-modal3999_f4505f-d3 .kt-modal-close svg, .kb-modal-content3999_f4505f-d3 .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal3999_f4505f-d3 .kt-modal-container, #kt-target-modal3999_f4505f-d3 .kt-modal-container, .kb-modal-content3999_f4505f-d3 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_f4505f-d3 .kt-modal-close svg, #kt-target-modal3999_f4505f-d3 .kt-modal-close svg, .kb-modal-content3999_f4505f-d3 .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center\" id=\"kt-modal3999_f4505f-d3\"><div id=\"kt-target-modal3999_f4505f-d3\" class=\"kb-modal-content3999_f4505f-d3 kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal3999_f4505f-d3-content\" class=\"kt-modal-content\">\n<p class=\"wp-block-paragraph\">Cordura<sup>\u00ae<\/sup> se ha convertido en sin\u00f3nimo de durabilidad en el mundo de las fibras de poliamida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta fibra es el resultado de un pol\u00edmero de \u00e1cido ad\u00edpico y hexametilendiamina que ampl\u00eda los l\u00edmites de resistencia del nailon. Con una resistencia al rasgado y a la abrasi\u00f3n significativamente superior, Cordura<sup>\u00ae<\/sup> se presta para productos que requieren una vida \u00fatil prolongada bajo condiciones de uso intensivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La versatilidad de Cordura<sup>\u00ae<\/sup> lo hace indispensable en una amplia gama de aplicaciones textiles, desde equipamiento t\u00e1ctico militar hasta art\u00edculos de uso diario como chaquetas de motociclismo, calzado robusto, mochilas resistentes y guantes de trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En IBQ, confiamos en Cordura<sup>\u00ae<\/sup> para desarrollar tejidos destinados a protecciones, piezas el\u00e1sticas y refuerzos, aprovechando su superioridad en resistencia a la abrasi\u00f3n &#8211; hasta diez veces mayor que la del algod\u00f3n &#8211; y su excepcional capacidad de resistir rasgaduras, caracter\u00edsticas esenciales para textiles que se someten a retos extremos.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal3999_f4505f-d3\"><span class=\"kt-blocks-modal-link-inner\">DESCUBRIR M\u00c1S<\/span><\/button><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_b49b1d-a3 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3999_b49b1d-a3 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column3999_b49b1d-a3 > .kt-inside-inner-col,.kadence-column3999_b49b1d-a3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_b49b1d-a3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_b49b1d-a3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_b49b1d-a3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_b49b1d-a3 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3999_b49b1d-a3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_b49b1d-a3{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_b49b1d-a3 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_b49b1d-a3 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_b49b1d-a3 partner-box\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image3999_810785-43:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image3999_810785-43.kb-image-is-ratio-size, .kb-image3999_810785-43 .kb-image-is-ratio-size{max-width:500px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_810785-43.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_810785-43 .kb-image-is-ratio-size{align-self:unset;}.kb-image3999_810785-43 figure{max-width:500px;}.kb-image3999_810785-43 .image-is-svg, .kb-image3999_810785-43 .image-is-svg img{width:100%;}.kb-image3999_810785-43 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3999_810785-43\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"410\" src=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-dupont-klevar-1024x410.png\" alt=\"\" class=\"kb-img wp-image-4846\" srcset=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-dupont-klevar-1024x410.png 1024w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-dupont-klevar-300x120.png 300w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-dupont-klevar-768x307.png 768w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-dupont-klevar.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3999_228560-fa, .wp-block-kadence-advancedheading.kt-adv-heading3999_228560-fa[data-kb-block=\"kb-adv-heading3999_228560-fa\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:24px;font-weight:400;font-style:normal;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;}.wp-block-kadence-advancedheading.kt-adv-heading3999_228560-fa mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_228560-fa[data-kb-block=\"kb-adv-heading3999_228560-fa\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading3999_228560-fa wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_228560-fa\">La sinergia de resistencia y ligereza<\/h3>\n\n\n<style>#kt-modal3999_a85473-ea .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette6, #718096);border-color:var(--global-palette6, #718096);border-radius:4px;font-size:12px;line-height:1.2;letter-spacing:2px;border-width:1px 1px 1px 1px;padding:8px 28px 8px 28px;margin:0px 0px 0px 0px;}#kt-modal3999_a85473-ea .kt-blocks-modal-link:hover, #kt-modal3999_a85473-ea .kt-blocks-modal-link:focus{color:#ffffff;background:#444444;border-color:#444444;}#kt-modal3999_a85473-ea .kt-modal-overlay, #kt-target-modal3999_a85473-ea .kt-modal-overlay, .kb-modal-content3999_a85473-ea .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal3999_a85473-ea .kt-modal-overlay, #kt-target-modal3999_a85473-ea .kt-modal-overlay, .kb-modal-content3999_a85473-ea .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal3999_a85473-ea .kt-modal-container, #kt-target-modal3999_a85473-ea .kt-modal-container, .kb-modal-content3999_a85473-ea .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal3999_a85473-ea .kt-modal-container, #kt-target-modal3999_a85473-ea .kt-modal-container, .kb-modal-content3999_a85473-ea .kt-modal-container{padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal3999_a85473-ea .kt-modal-container, #kt-target-modal3999_a85473-ea .kt-modal-container, .kb-modal-content3999_a85473-ea .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_a85473-ea .kt-modal-close svg, #kt-target-modal3999_a85473-ea .kt-modal-close svg, .kb-modal-content3999_a85473-ea .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal3999_a85473-ea .kt-modal-container, #kt-target-modal3999_a85473-ea .kt-modal-container, .kb-modal-content3999_a85473-ea .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal3999_a85473-ea .kt-modal-close svg, #kt-target-modal3999_a85473-ea .kt-modal-close svg, .kb-modal-content3999_a85473-ea .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal3999_a85473-ea .kt-modal-container, #kt-target-modal3999_a85473-ea .kt-modal-container, .kb-modal-content3999_a85473-ea .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_a85473-ea .kt-modal-close svg, #kt-target-modal3999_a85473-ea .kt-modal-close svg, .kb-modal-content3999_a85473-ea .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center\" id=\"kt-modal3999_a85473-ea\"><div id=\"kt-target-modal3999_a85473-ea\" class=\"kb-modal-content3999_a85473-ea kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal3999_a85473-ea-content\" class=\"kt-modal-content\">\n<p class=\"wp-block-paragraph\">Kevlar<sup>\u00ae<\/sup> es una poliamida que redefine las expectativas de resistencia en los textiles t\u00e9cnicos. Este pol\u00edmero forma la base de hilos de excepcional tenacidad, capaces de absorber impactos y resistir temperaturas extremas. El Kevlar<sup>\u00ae<\/sup> es fundamental para prendas y materiales que demandan una protecci\u00f3n insuperable, tales como armaduras corporales y refuerzos industriales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su formidable resistencia a la tracci\u00f3n -ocho veces superior a la del acero-combinada con una sorprendente ligereza, hace de Kevlar<sup>\u00ae<\/sup> el aliado perfecto en la creaci\u00f3n de textiles robustos sin a\u00f1adir peso innecesario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este material se descompone entre los 420 y 480 \u00b0C, conservando su integridad casi intacta hasta alcanzar esos l\u00edmites. Asimismo, su rendimiento en fr\u00edo es excepcional, con m\u00ednima degradaci\u00f3n incluso a -195 \u00b0C.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En IBQ, aprovechamos la resistencia qu\u00edmica de Kevlar<sup>\u00ae<\/sup> para desarrollar tejidos que soportan una variedad de sustancias sin deteriorarse, una propiedad crucial para aplicaciones en entornos con exposici\u00f3n a disolventes y aceites. Aunque se ve afectado por \u00e1cidos o bases fuertes durante exposiciones prolongadas, su rendimiento general permanece destacado. La robustez de Kevlar<sup>\u00ae<\/sup> se evidencia en la dificultad para separar sus mol\u00e9culas, requiriendo una cantidad significativa de energ\u00eda para romperlas.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal3999_a85473-ea\"><span class=\"kt-blocks-modal-link-inner\">DESCUBRIR M\u00c1S<\/span><\/button><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_f20068-a8 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3999_f20068-a8 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column3999_f20068-a8 > .kt-inside-inner-col,.kadence-column3999_f20068-a8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_f20068-a8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_f20068-a8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_f20068-a8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_f20068-a8 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3999_f20068-a8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_f20068-a8{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_f20068-a8 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_f20068-a8 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_f20068-a8 partner-box\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image3999_ded286-0d:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image3999_ded286-0d.kb-image-is-ratio-size, .kb-image3999_ded286-0d .kb-image-is-ratio-size{max-width:500px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_ded286-0d.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_ded286-0d .kb-image-is-ratio-size{align-self:unset;}.kb-image3999_ded286-0d figure{max-width:500px;}.kb-image3999_ded286-0d .image-is-svg, .kb-image3999_ded286-0d .image-is-svg img{width:100%;}.kb-image3999_ded286-0d .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3999_ded286-0d\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"410\" src=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-coolmax-1024x410.png\" alt=\"\" class=\"kb-img wp-image-4847\" srcset=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-coolmax-1024x410.png 1024w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-coolmax-300x120.png 300w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-coolmax-768x307.png 768w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-coolmax.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3999_bbae4d-aa, .wp-block-kadence-advancedheading.kt-adv-heading3999_bbae4d-aa[data-kb-block=\"kb-adv-heading3999_bbae4d-aa\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:24px;font-weight:400;font-style:normal;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;}.wp-block-kadence-advancedheading.kt-adv-heading3999_bbae4d-aa mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_bbae4d-aa[data-kb-block=\"kb-adv-heading3999_bbae4d-aa\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading3999_bbae4d-aa wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_bbae4d-aa\">Innovaci\u00f3n en confort y transpirabilidad<\/h3>\n\n\n<style>#kt-modal3999_4fe400-1c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette6, #718096);border-color:var(--global-palette6, #718096);border-radius:4px;font-size:12px;line-height:1.2;letter-spacing:2px;border-width:1px 1px 1px 1px;padding:8px 28px 8px 28px;margin:0px 0px 0px 0px;}#kt-modal3999_4fe400-1c .kt-blocks-modal-link:hover, #kt-modal3999_4fe400-1c .kt-blocks-modal-link:focus{color:#ffffff;background:#444444;border-color:#444444;}#kt-modal3999_4fe400-1c .kt-modal-overlay, #kt-target-modal3999_4fe400-1c .kt-modal-overlay, .kb-modal-content3999_4fe400-1c .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal3999_4fe400-1c .kt-modal-overlay, #kt-target-modal3999_4fe400-1c .kt-modal-overlay, .kb-modal-content3999_4fe400-1c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal3999_4fe400-1c .kt-modal-container, #kt-target-modal3999_4fe400-1c .kt-modal-container, .kb-modal-content3999_4fe400-1c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal3999_4fe400-1c .kt-modal-container, #kt-target-modal3999_4fe400-1c .kt-modal-container, .kb-modal-content3999_4fe400-1c .kt-modal-container{padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal3999_4fe400-1c .kt-modal-container, #kt-target-modal3999_4fe400-1c .kt-modal-container, .kb-modal-content3999_4fe400-1c .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_4fe400-1c .kt-modal-close svg, #kt-target-modal3999_4fe400-1c .kt-modal-close svg, .kb-modal-content3999_4fe400-1c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal3999_4fe400-1c .kt-modal-container, #kt-target-modal3999_4fe400-1c .kt-modal-container, .kb-modal-content3999_4fe400-1c .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal3999_4fe400-1c .kt-modal-close svg, #kt-target-modal3999_4fe400-1c .kt-modal-close svg, .kb-modal-content3999_4fe400-1c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal3999_4fe400-1c .kt-modal-container, #kt-target-modal3999_4fe400-1c .kt-modal-container, .kb-modal-content3999_4fe400-1c .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_4fe400-1c .kt-modal-close svg, #kt-target-modal3999_4fe400-1c .kt-modal-close svg, .kb-modal-content3999_4fe400-1c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center\" id=\"kt-modal3999_4fe400-1c\"><div id=\"kt-target-modal3999_4fe400-1c\" class=\"kb-modal-content3999_4fe400-1c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal3999_4fe400-1c-content\" class=\"kt-modal-content\">\n<p class=\"wp-block-paragraph\">COOLMAX<sup>\u00ae<\/sup> transforma el concepto de ropa deportiva y de trabajo mediante sus avanzados poli\u00e9steres, dise\u00f1ados para ofrecer una transpirabilidad sin precedentes. Esta fibra se destaca por su habilidad \u00fanica para facilitar la evaporaci\u00f3n del sudor, manteniendo al usuario fresco y seco incluso bajo esfuerzo intenso o condiciones de calor extremo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tecnolog\u00eda detr\u00e1s de COOLMAX<sup>\u00ae<\/sup> se integra perfectamente a nuestra gama de tejidos, especialmente en aquellos destinados a refuerzos y textiles el\u00e1sticos que requieren una alta capacidad de ventilaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La estructura de las fibras, con canales especificos para la aireaci\u00f3n, permite que el sudor se disperse r\u00e1pidamente y se evapore, optimizando as\u00ed el control de la temperatura y el confort durante el uso prolongado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de su sobresaliente transpirabilidad, COOLMAX<sup>\u00ae<\/sup> ofrece una resistencia superior a la humedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dise\u00f1ada para transportar eficazmente la humedad lejos del cuerpo, esta fibra asegura que las prendas no solo se mantengan ligeras y c\u00f3modas, sino que tambi\u00e9n se sequen r\u00e1pidamente. Esta caracter\u00edstica es esencial para vestimentas deportivas y de trabajo, donde la gesti\u00f3n eficiente de la humedad es clave para mantener el rendimiento y la comodidad a lo largo del d\u00eda.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal3999_4fe400-1c\"><span class=\"kt-blocks-modal-link-inner\">DESCUBRIR M\u00c1S<\/span><\/button><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_b89c68-4a > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3999_b89c68-4a > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column3999_b89c68-4a > .kt-inside-inner-col,.kadence-column3999_b89c68-4a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_b89c68-4a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_b89c68-4a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_b89c68-4a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_b89c68-4a > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3999_b89c68-4a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_b89c68-4a{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_b89c68-4a > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_b89c68-4a > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_b89c68-4a partner-box\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image3999_a5bde1-3d:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image3999_a5bde1-3d.kb-image-is-ratio-size, .kb-image3999_a5bde1-3d .kb-image-is-ratio-size{max-width:500px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_a5bde1-3d.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_a5bde1-3d .kb-image-is-ratio-size{align-self:unset;}.kb-image3999_a5bde1-3d figure{max-width:500px;}.kb-image3999_a5bde1-3d .image-is-svg, .kb-image3999_a5bde1-3d .image-is-svg img{width:100%;}.kb-image3999_a5bde1-3d .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3999_a5bde1-3d\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"410\" src=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-econyl-1024x410.png\" alt=\"\" class=\"kb-img wp-image-4848\" srcset=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-econyl-1024x410.png 1024w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-econyl-300x120.png 300w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-econyl-768x307.png 768w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-econyl.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3999_e7369f-41, .wp-block-kadence-advancedheading.kt-adv-heading3999_e7369f-41[data-kb-block=\"kb-adv-heading3999_e7369f-41\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:24px;font-weight:400;font-style:normal;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;}.wp-block-kadence-advancedheading.kt-adv-heading3999_e7369f-41 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_e7369f-41[data-kb-block=\"kb-adv-heading3999_e7369f-41\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading3999_e7369f-41 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_e7369f-41\">Sostenibilidad y rendimiento sin compromisos<\/h3>\n\n\n<style>#kt-modal3999_2c0d07-aa .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette6, #718096);border-color:var(--global-palette6, #718096);border-radius:4px;font-size:12px;line-height:1.2;letter-spacing:2px;border-width:1px 1px 1px 1px;padding:8px 28px 8px 28px;margin:0px 0px 0px 0px;}#kt-modal3999_2c0d07-aa .kt-blocks-modal-link:hover, #kt-modal3999_2c0d07-aa .kt-blocks-modal-link:focus{color:#ffffff;background:#444444;border-color:#444444;}#kt-modal3999_2c0d07-aa .kt-modal-overlay, #kt-target-modal3999_2c0d07-aa .kt-modal-overlay, .kb-modal-content3999_2c0d07-aa .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal3999_2c0d07-aa .kt-modal-overlay, #kt-target-modal3999_2c0d07-aa .kt-modal-overlay, .kb-modal-content3999_2c0d07-aa .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal3999_2c0d07-aa .kt-modal-container, #kt-target-modal3999_2c0d07-aa .kt-modal-container, .kb-modal-content3999_2c0d07-aa .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal3999_2c0d07-aa .kt-modal-container, #kt-target-modal3999_2c0d07-aa .kt-modal-container, .kb-modal-content3999_2c0d07-aa .kt-modal-container{padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal3999_2c0d07-aa .kt-modal-container, #kt-target-modal3999_2c0d07-aa .kt-modal-container, .kb-modal-content3999_2c0d07-aa .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_2c0d07-aa .kt-modal-close svg, #kt-target-modal3999_2c0d07-aa .kt-modal-close svg, .kb-modal-content3999_2c0d07-aa .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal3999_2c0d07-aa .kt-modal-container, #kt-target-modal3999_2c0d07-aa .kt-modal-container, .kb-modal-content3999_2c0d07-aa .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal3999_2c0d07-aa .kt-modal-close svg, #kt-target-modal3999_2c0d07-aa .kt-modal-close svg, .kb-modal-content3999_2c0d07-aa .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal3999_2c0d07-aa .kt-modal-container, #kt-target-modal3999_2c0d07-aa .kt-modal-container, .kb-modal-content3999_2c0d07-aa .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_2c0d07-aa .kt-modal-close svg, #kt-target-modal3999_2c0d07-aa .kt-modal-close svg, .kb-modal-content3999_2c0d07-aa .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center\" id=\"kt-modal3999_2c0d07-aa\"><div id=\"kt-target-modal3999_2c0d07-aa\" class=\"kb-modal-content3999_2c0d07-aa kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal3999_2c0d07-aa-content\" class=\"kt-modal-content\">\n<p class=\"wp-block-paragraph\">Econyl<sup>\u00ae<\/sup> redefine la producci\u00f3n textil con su hilo 100% reciclado, creado a partir de desechos de nylon, incluyendo redes de pesca recuperadas de los oc\u00e9anos. Esta innovadora reinvenci\u00f3n no solo contribuye a la limpieza de nuestros mares, sino que tambi\u00e9n ofrece un hilo con las mismas propiedades destacadas del nylon virgen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La versatilidad de Econyl<sup>\u00ae<\/sup> lo hace ideal para una amplia gama de aplicaciones, desde ropa ajustada como medias y mallas, hasta ropa deportiva y trajes de ba\u00f1o. Su resistencia y elasticidad excepcionales aseguran un ajuste perfecto y de alta durabilidad, mientras que su capacidad para repeler el agua, hace de Econyl<sup>\u00ae<\/sup> una elecci\u00f3n excelente para prendas exteriores y de rendimiento acu\u00e1tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al elegir Econyl<sup>\u00ae<\/sup>, no solo nos comprometemos con la calidad y la funcionalidad, sino tambi\u00e9n con la sostenibilidad y la protecci\u00f3n del medio ambiente. Este hilo representa nuestro esfuerzo por ofrecer productos que no solo satisfacen las necesidades de nuestros clientes, sino que tambi\u00e9n contribuyen a un futuro m\u00e1s verde.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal3999_2c0d07-aa\"><span class=\"kt-blocks-modal-link-inner\">DESCUBRIR M\u00c1S<\/span><\/button><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_5344b8-57 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3999_5344b8-57 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column3999_5344b8-57 > .kt-inside-inner-col,.kadence-column3999_5344b8-57 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_5344b8-57 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_5344b8-57 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_5344b8-57 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_5344b8-57 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3999_5344b8-57 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_5344b8-57{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_5344b8-57 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_5344b8-57 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_5344b8-57 partner-box\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image3999_79289e-94:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image3999_79289e-94.kb-image-is-ratio-size, .kb-image3999_79289e-94 .kb-image-is-ratio-size{max-width:500px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_79289e-94.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_79289e-94 .kb-image-is-ratio-size{align-self:unset;}.kb-image3999_79289e-94 figure{max-width:500px;}.kb-image3999_79289e-94 .image-is-svg, .kb-image3999_79289e-94 .image-is-svg img{width:100%;}.kb-image3999_79289e-94 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3999_79289e-94\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"410\" src=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-sensil-breeze-1024x410.png\" alt=\"\" class=\"kb-img wp-image-4849\" srcset=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-sensil-breeze-1024x410.png 1024w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-sensil-breeze-300x120.png 300w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-sensil-breeze-768x307.png 768w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-sensil-breeze.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3999_60c06a-2c, .wp-block-kadence-advancedheading.kt-adv-heading3999_60c06a-2c[data-kb-block=\"kb-adv-heading3999_60c06a-2c\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:24px;font-weight:400;font-style:normal;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;}.wp-block-kadence-advancedheading.kt-adv-heading3999_60c06a-2c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_60c06a-2c[data-kb-block=\"kb-adv-heading3999_60c06a-2c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading3999_60c06a-2c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_60c06a-2c\">Confort y frescura avanzados<\/h3>\n\n\n<style>#kt-modal3999_0379b5-f6 .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette6, #718096);border-color:var(--global-palette6, #718096);border-radius:4px;font-size:12px;line-height:1.2;letter-spacing:2px;border-width:1px 1px 1px 1px;padding:8px 28px 8px 28px;margin:0px 0px 0px 0px;}#kt-modal3999_0379b5-f6 .kt-blocks-modal-link:hover, #kt-modal3999_0379b5-f6 .kt-blocks-modal-link:focus{color:#ffffff;background:#444444;border-color:#444444;}#kt-modal3999_0379b5-f6 .kt-modal-overlay, #kt-target-modal3999_0379b5-f6 .kt-modal-overlay, .kb-modal-content3999_0379b5-f6 .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal3999_0379b5-f6 .kt-modal-overlay, #kt-target-modal3999_0379b5-f6 .kt-modal-overlay, .kb-modal-content3999_0379b5-f6 .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal3999_0379b5-f6 .kt-modal-container, #kt-target-modal3999_0379b5-f6 .kt-modal-container, .kb-modal-content3999_0379b5-f6 .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal3999_0379b5-f6 .kt-modal-container, #kt-target-modal3999_0379b5-f6 .kt-modal-container, .kb-modal-content3999_0379b5-f6 .kt-modal-container{padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal3999_0379b5-f6 .kt-modal-container, #kt-target-modal3999_0379b5-f6 .kt-modal-container, .kb-modal-content3999_0379b5-f6 .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_0379b5-f6 .kt-modal-close svg, #kt-target-modal3999_0379b5-f6 .kt-modal-close svg, .kb-modal-content3999_0379b5-f6 .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal3999_0379b5-f6 .kt-modal-container, #kt-target-modal3999_0379b5-f6 .kt-modal-container, .kb-modal-content3999_0379b5-f6 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal3999_0379b5-f6 .kt-modal-close svg, #kt-target-modal3999_0379b5-f6 .kt-modal-close svg, .kb-modal-content3999_0379b5-f6 .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal3999_0379b5-f6 .kt-modal-container, #kt-target-modal3999_0379b5-f6 .kt-modal-container, .kb-modal-content3999_0379b5-f6 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_0379b5-f6 .kt-modal-close svg, #kt-target-modal3999_0379b5-f6 .kt-modal-close svg, .kb-modal-content3999_0379b5-f6 .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center\" id=\"kt-modal3999_0379b5-f6\"><div id=\"kt-target-modal3999_0379b5-f6\" class=\"kb-modal-content3999_0379b5-f6 kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal3999_0379b5-f6-content\" class=\"kt-modal-content\">\n<p class=\"wp-block-paragraph\">SENSIL<sup>\u00ae<\/sup> BREEZE es un hilo de vanguardia dise\u00f1ado para mantener la piel fresca y confortable, incluso bajo condiciones de alta temperatura o durante actividades f\u00edsicas intensas. Su estructura \u00fanica no solo es flexible y suave al tacto, sino que tambi\u00e9n brinda un apoyo y resistencia excepcionales, asegurando prendas duraderas y c\u00f3modas para el uso diario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a su estructura de secci\u00f3n transversal plana, SENSIL<sup>\u00ae<\/sup> BREEZE facilita una eficiente transferencia de calor lejos del cuerpo, contribuyendo a una sensaci\u00f3n refrescante inmediata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este efecto se complementa con propiedades antibacterianas y de resistencia a la humedad, protegiendo la piel y manteniendo las prendas secas y frescas durante m\u00e1s tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso especial de texturizaci\u00f3n confiere al hilo una ligereza \u00fanica, permitiendo que las prendas ofrezcan la m\u00e1xima transpirabilidad y ventilaci\u00f3n. Ideal para la ropa deportiva y de ocio,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SENSIL<sup>\u00ae<\/sup> BREEZE mejora la experiencia del usuario al mantener una temperatura corporal agradable, tanto durante el esfuerzo f\u00edsico como en la relajaci\u00f3n posterior, en cualquier clima.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal3999_0379b5-f6\"><span class=\"kt-blocks-modal-link-inner\">DESCUBRIR M\u00c1S<\/span><\/button><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_d9c0bc-5d > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3999_d9c0bc-5d > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column3999_d9c0bc-5d > .kt-inside-inner-col,.kadence-column3999_d9c0bc-5d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_d9c0bc-5d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_d9c0bc-5d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_d9c0bc-5d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_d9c0bc-5d > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3999_d9c0bc-5d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_d9c0bc-5d{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_d9c0bc-5d > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_d9c0bc-5d > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_d9c0bc-5d partner-box\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image3999_72aca3-43:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image3999_72aca3-43.kb-image-is-ratio-size, .kb-image3999_72aca3-43 .kb-image-is-ratio-size{max-width:500px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_72aca3-43.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_72aca3-43 .kb-image-is-ratio-size{align-self:unset;}.kb-image3999_72aca3-43 figure{max-width:500px;}.kb-image3999_72aca3-43 .image-is-svg, .kb-image3999_72aca3-43 .image-is-svg img{width:100%;}.kb-image3999_72aca3-43 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3999_72aca3-43\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"410\" src=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-sensil-heat-1024x410.png\" alt=\"\" class=\"kb-img wp-image-4850\" srcset=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-sensil-heat-1024x410.png 1024w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-sensil-heat-300x120.png 300w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-sensil-heat-768x307.png 768w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-sensil-heat.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3999_09f711-64, .wp-block-kadence-advancedheading.kt-adv-heading3999_09f711-64[data-kb-block=\"kb-adv-heading3999_09f711-64\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:24px;font-weight:400;font-style:normal;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;}.wp-block-kadence-advancedheading.kt-adv-heading3999_09f711-64 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_09f711-64[data-kb-block=\"kb-adv-heading3999_09f711-64\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading3999_09f711-64 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_09f711-64\">Calidez innovadora para el confort total<\/h3>\n\n\n<style>#kt-modal3999_01ce5a-8a .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette6, #718096);border-color:var(--global-palette6, #718096);border-radius:4px;font-size:12px;line-height:1.2;letter-spacing:2px;border-width:1px 1px 1px 1px;padding:8px 28px 8px 28px;margin:0px 0px 0px 0px;}#kt-modal3999_01ce5a-8a .kt-blocks-modal-link:hover, #kt-modal3999_01ce5a-8a .kt-blocks-modal-link:focus{color:#ffffff;background:#444444;border-color:#444444;}#kt-modal3999_01ce5a-8a .kt-modal-overlay, #kt-target-modal3999_01ce5a-8a .kt-modal-overlay, .kb-modal-content3999_01ce5a-8a .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal3999_01ce5a-8a .kt-modal-overlay, #kt-target-modal3999_01ce5a-8a .kt-modal-overlay, .kb-modal-content3999_01ce5a-8a .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal3999_01ce5a-8a .kt-modal-container, #kt-target-modal3999_01ce5a-8a .kt-modal-container, .kb-modal-content3999_01ce5a-8a .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal3999_01ce5a-8a .kt-modal-container, #kt-target-modal3999_01ce5a-8a .kt-modal-container, .kb-modal-content3999_01ce5a-8a .kt-modal-container{padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal3999_01ce5a-8a .kt-modal-container, #kt-target-modal3999_01ce5a-8a .kt-modal-container, .kb-modal-content3999_01ce5a-8a .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_01ce5a-8a .kt-modal-close svg, #kt-target-modal3999_01ce5a-8a .kt-modal-close svg, .kb-modal-content3999_01ce5a-8a .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal3999_01ce5a-8a .kt-modal-container, #kt-target-modal3999_01ce5a-8a .kt-modal-container, .kb-modal-content3999_01ce5a-8a .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal3999_01ce5a-8a .kt-modal-close svg, #kt-target-modal3999_01ce5a-8a .kt-modal-close svg, .kb-modal-content3999_01ce5a-8a .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal3999_01ce5a-8a .kt-modal-container, #kt-target-modal3999_01ce5a-8a .kt-modal-container, .kb-modal-content3999_01ce5a-8a .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_01ce5a-8a .kt-modal-close svg, #kt-target-modal3999_01ce5a-8a .kt-modal-close svg, .kb-modal-content3999_01ce5a-8a .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center\" id=\"kt-modal3999_01ce5a-8a\"><div id=\"kt-target-modal3999_01ce5a-8a\" class=\"kb-modal-content3999_01ce5a-8a kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal3999_01ce5a-8a-content\" class=\"kt-modal-content\">\n<p class=\"wp-block-paragraph\">SENSIL<sup>\u00ae<\/sup> HEAT es una fibra revolucionaria que redefine el concepto de ropa de abrigo. Dise\u00f1ada para capturar y retener el calor corporal, esta avanzada fibra incorpora un aditivo \u00fanico de \u00f3xido y carb\u00f3n de caf\u00e9, optimizando la gesti\u00f3n del calor para un confort prolongado en climas fr\u00edos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta tecnolog\u00eda no solo preserva la calidez natural del cuerpo, sino que tambi\u00e9n maneja eficazmente la humedad y neutraliza los olores, garantizando as\u00ed una experiencia de usuario excepcionalmente confortable y fresca. El proceso de texturizaci\u00f3n especial de SENSIL\u00ae HEAT produce un hilo de bajo volumen, lo que resulta en prendas altamente transpirables y ventiladas, ideales para mantener la temperatura corporal sin sacrificar la ligereza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SENSIL<sup>\u00ae<\/sup> HEAT es la soluci\u00f3n perfecta para quienes buscan mantenerse calientes sin la incomodidad de las prendas pesadas. Ya sea para actividades al aire libre en invierno o para el d\u00eda a d\u00eda en ambientes fr\u00edos, las prendas con SENSIL<sup>\u00ae<\/sup> HEAT ofrecen un equilibrio ideal entre calidez, comodidad y funcionalidad, manteniendo al usuario c\u00e1lido y confortable en todo momento.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal3999_01ce5a-8a\"><span class=\"kt-blocks-modal-link-inner\">DESCUBRIR M\u00c1S<\/span><\/button><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_e8dd3a-79 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3999_e8dd3a-79 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column3999_e8dd3a-79 > .kt-inside-inner-col,.kadence-column3999_e8dd3a-79 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_e8dd3a-79 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_e8dd3a-79 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_e8dd3a-79 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_e8dd3a-79 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3999_e8dd3a-79 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_e8dd3a-79{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_e8dd3a-79 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_e8dd3a-79 > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_e8dd3a-79 partner-box\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image3999_4399ef-ae:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image3999_4399ef-ae.kb-image-is-ratio-size, .kb-image3999_4399ef-ae .kb-image-is-ratio-size{max-width:500px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_4399ef-ae.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_4399ef-ae .kb-image-is-ratio-size{align-self:unset;}.kb-image3999_4399ef-ae figure{max-width:500px;}.kb-image3999_4399ef-ae .image-is-svg, .kb-image3999_4399ef-ae .image-is-svg img{width:100%;}.kb-image3999_4399ef-ae .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3999_4399ef-ae\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"410\" src=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-lycra-1024x410.png\" alt=\"\" class=\"kb-img wp-image-4851\" srcset=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-lycra-1024x410.png 1024w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-lycra-300x120.png 300w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-lycra-768x307.png 768w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-lycra.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3999_9ee60a-bf, .wp-block-kadence-advancedheading.kt-adv-heading3999_9ee60a-bf[data-kb-block=\"kb-adv-heading3999_9ee60a-bf\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:24px;font-weight:400;font-style:normal;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;}.wp-block-kadence-advancedheading.kt-adv-heading3999_9ee60a-bf mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_9ee60a-bf[data-kb-block=\"kb-adv-heading3999_9ee60a-bf\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading3999_9ee60a-bf wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_9ee60a-bf\">Flexibilidad y durabilidad sin compromisos<\/h3>\n\n\n<style>#kt-modal3999_1dffa1-43 .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette6, #718096);border-color:var(--global-palette6, #718096);border-radius:4px;font-size:12px;line-height:1.2;letter-spacing:2px;border-width:1px 1px 1px 1px;padding:8px 28px 8px 28px;margin:0px 0px 0px 0px;}#kt-modal3999_1dffa1-43 .kt-blocks-modal-link:hover, #kt-modal3999_1dffa1-43 .kt-blocks-modal-link:focus{color:#ffffff;background:#444444;border-color:#444444;}#kt-modal3999_1dffa1-43 .kt-modal-overlay, #kt-target-modal3999_1dffa1-43 .kt-modal-overlay, .kb-modal-content3999_1dffa1-43 .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal3999_1dffa1-43 .kt-modal-overlay, #kt-target-modal3999_1dffa1-43 .kt-modal-overlay, .kb-modal-content3999_1dffa1-43 .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal3999_1dffa1-43 .kt-modal-container, #kt-target-modal3999_1dffa1-43 .kt-modal-container, .kb-modal-content3999_1dffa1-43 .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal3999_1dffa1-43 .kt-modal-container, #kt-target-modal3999_1dffa1-43 .kt-modal-container, .kb-modal-content3999_1dffa1-43 .kt-modal-container{padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal3999_1dffa1-43 .kt-modal-container, #kt-target-modal3999_1dffa1-43 .kt-modal-container, .kb-modal-content3999_1dffa1-43 .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_1dffa1-43 .kt-modal-close svg, #kt-target-modal3999_1dffa1-43 .kt-modal-close svg, .kb-modal-content3999_1dffa1-43 .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal3999_1dffa1-43 .kt-modal-container, #kt-target-modal3999_1dffa1-43 .kt-modal-container, .kb-modal-content3999_1dffa1-43 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal3999_1dffa1-43 .kt-modal-close svg, #kt-target-modal3999_1dffa1-43 .kt-modal-close svg, .kb-modal-content3999_1dffa1-43 .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal3999_1dffa1-43 .kt-modal-container, #kt-target-modal3999_1dffa1-43 .kt-modal-container, .kb-modal-content3999_1dffa1-43 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_1dffa1-43 .kt-modal-close svg, #kt-target-modal3999_1dffa1-43 .kt-modal-close svg, .kb-modal-content3999_1dffa1-43 .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center\" id=\"kt-modal3999_1dffa1-43\"><div id=\"kt-target-modal3999_1dffa1-43\" class=\"kb-modal-content3999_1dffa1-43 kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal3999_1dffa1-43-content\" class=\"kt-modal-content\">\n<p class=\"wp-block-paragraph\">Lycra<sup>\u00ae<\/sup> es sin\u00f3nimo de adaptabilidad v rendimiento en el mundo textil, destacando por su capacidad excepcional de estiramiento y recuperaci\u00f3n. Esta fibra se extiende varias veces m\u00e1s all\u00e1 de su tama\u00f1o original, para luego volver a su forma sin perder integridad, lo que la convierte en un componente esencial para prendas que requieren una alta flexibilidad y comodidad duradera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de su notable elasticidad, Lycra<sup>\u00ae<\/sup> es ligera y resistente, capaz de soportar el desgaste diario sin sacrificar su forma o calidad. Su facilidad para te\u00f1ir y resistencia a la abrasi\u00f3n y al prensado, hacen de Lycra<sup>\u00ae<\/sup> una elecci\u00f3n ideal para una amplia gama de aplicaciones, desde ropa deportiva hasta moda diaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La capacidad de Lycra\u00ae para gestionar la humedad aleja el sudor de la piel, manteniendo al usuario seco y c\u00f3modo, una caracter\u00edstica apreciada en cualquier situaci\u00f3n. Su versatilidad se extiende a\u00fan m\u00e1s al poder combinarse con diversas fibras, tanto naturales como sint\u00e9ticas, mejorando la elasticidad de los tejidos sin alterar su aspecto o tacto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incorporando Lycra<sup>\u00ae<\/sup> en nuestros tejidos, garantizamos una experiencia inigualable de confort y libertad de movimiento, marcando la diferencia en la calidad y el rendimiento de las prendas.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal3999_1dffa1-43\"><span class=\"kt-blocks-modal-link-inner\">DESCUBRIR M\u00c1S<\/span><\/button><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_622ece-ce > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3999_622ece-ce > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column3999_622ece-ce > .kt-inside-inner-col,.kadence-column3999_622ece-ce > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_622ece-ce > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_622ece-ce > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_622ece-ce > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_622ece-ce > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3999_622ece-ce > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_622ece-ce{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_622ece-ce > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_622ece-ce > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_622ece-ce partner-box\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image3999_488db1-be:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image3999_488db1-be.kb-image-is-ratio-size, .kb-image3999_488db1-be .kb-image-is-ratio-size{max-width:500px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_488db1-be.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_488db1-be .kb-image-is-ratio-size{align-self:unset;}.kb-image3999_488db1-be figure{max-width:500px;}.kb-image3999_488db1-be .image-is-svg, .kb-image3999_488db1-be .image-is-svg img{width:100%;}.kb-image3999_488db1-be .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3999_488db1-be\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"410\" src=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-eurepean-fax-1024x410.png\" alt=\"\" class=\"kb-img wp-image-4852\" srcset=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-eurepean-fax-1024x410.png 1024w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-eurepean-fax-300x120.png 300w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-eurepean-fax-768x307.png 768w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-eurepean-fax.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3999_ce3463-60, .wp-block-kadence-advancedheading.kt-adv-heading3999_ce3463-60[data-kb-block=\"kb-adv-heading3999_ce3463-60\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:24px;font-weight:400;font-style:normal;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;}.wp-block-kadence-advancedheading.kt-adv-heading3999_ce3463-60 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_ce3463-60[data-kb-block=\"kb-adv-heading3999_ce3463-60\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading3999_ce3463-60 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_ce3463-60\">Tradici\u00f3n y sostenibilidad<\/h3>\n\n\n<style>#kt-modal3999_1ac357-05 .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette6, #718096);border-color:var(--global-palette6, #718096);border-radius:4px;font-size:12px;line-height:1.2;letter-spacing:2px;border-width:1px 1px 1px 1px;padding:8px 28px 8px 28px;margin:0px 0px 0px 0px;}#kt-modal3999_1ac357-05 .kt-blocks-modal-link:hover, #kt-modal3999_1ac357-05 .kt-blocks-modal-link:focus{color:#ffffff;background:#444444;border-color:#444444;}#kt-modal3999_1ac357-05 .kt-modal-overlay, #kt-target-modal3999_1ac357-05 .kt-modal-overlay, .kb-modal-content3999_1ac357-05 .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal3999_1ac357-05 .kt-modal-overlay, #kt-target-modal3999_1ac357-05 .kt-modal-overlay, .kb-modal-content3999_1ac357-05 .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal3999_1ac357-05 .kt-modal-container, #kt-target-modal3999_1ac357-05 .kt-modal-container, .kb-modal-content3999_1ac357-05 .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal3999_1ac357-05 .kt-modal-container, #kt-target-modal3999_1ac357-05 .kt-modal-container, .kb-modal-content3999_1ac357-05 .kt-modal-container{padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal3999_1ac357-05 .kt-modal-container, #kt-target-modal3999_1ac357-05 .kt-modal-container, .kb-modal-content3999_1ac357-05 .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_1ac357-05 .kt-modal-close svg, #kt-target-modal3999_1ac357-05 .kt-modal-close svg, .kb-modal-content3999_1ac357-05 .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal3999_1ac357-05 .kt-modal-container, #kt-target-modal3999_1ac357-05 .kt-modal-container, .kb-modal-content3999_1ac357-05 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal3999_1ac357-05 .kt-modal-close svg, #kt-target-modal3999_1ac357-05 .kt-modal-close svg, .kb-modal-content3999_1ac357-05 .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal3999_1ac357-05 .kt-modal-container, #kt-target-modal3999_1ac357-05 .kt-modal-container, .kb-modal-content3999_1ac357-05 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_1ac357-05 .kt-modal-close svg, #kt-target-modal3999_1ac357-05 .kt-modal-close svg, .kb-modal-content3999_1ac357-05 .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center\" id=\"kt-modal3999_1ac357-05\"><div id=\"kt-target-modal3999_1ac357-05\" class=\"kb-modal-content3999_1ac357-05 kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal3999_1ac357-05-content\" class=\"kt-modal-content\">\n<p class=\"wp-block-paragraph\">EUROPEAN FLAX<sup>\u00ae<\/sup> LINEN destaca en el mundo textil por su excelencia en calidad y su compromiso con pr\u00e1cticas de producci\u00f3n sostenibles. Esta fibra, cultivada sin riego artificial y sin OGM (Organismos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gen\u00e9ticamente Modificados) en el coraz\u00f3n de Europa, representa el est\u00e1ndar de oro en lino. Es ampliamente valorado por su durabilidad natural y su incre\u00edble capacidad de mejorar con el tiempo. Cada lavado suaviza la fibra sin comprometer su integridad, lo que se traduce en prendas que no solo son resistentes, sino tambi\u00e9n increiblemente c\u00f3modas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comprometido con la sostenibilidad, EUROPEAN FLAX<sup>\u00ae<\/sup> LINEN es 100% biodegradable y reciclable, reduciendo as\u00ed su impacto ambiental. Su producci\u00f3n respeta el medio ambiente y promueve la biodiversidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de pr\u00e1ctico, tambi\u00e9n es est\u00e9ticamente vers\u00e1til. Se puede te\u00f1ir en una amplia gama de colores y se integra f\u00e1cilmente con otras fibras, proporcionando una textura rica y una ca\u00edda elegante que realza cualquier dise\u00f1o de moda. Su capacidad para regular la temperatura hace que las prendas de lino sean perfectamente adecuadas para cualquier estaci\u00f3n, ofreciendo frescura en verano y confort en invierno.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal3999_1ac357-05\"><span class=\"kt-blocks-modal-link-inner\">DESCUBRIR M\u00c1S<\/span><\/button><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3999_bac823-4a > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column3999_bac823-4a > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kadence-column3999_bac823-4a > .kt-inside-inner-col,.kadence-column3999_bac823-4a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_bac823-4a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_bac823-4a > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_bac823-4a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_bac823-4a > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column3999_bac823-4a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_bac823-4a{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_bac823-4a > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_bac823-4a > .kt-inside-inner-col{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_bac823-4a partner-box\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image3999_732440-34:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image3999_732440-34.kb-image-is-ratio-size, .kb-image3999_732440-34 .kb-image-is-ratio-size{max-width:500px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_732440-34.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3999_732440-34 .kb-image-is-ratio-size{align-self:unset;}.kb-image3999_732440-34 figure{max-width:500px;}.kb-image3999_732440-34 .image-is-svg, .kb-image3999_732440-34 .image-is-svg img{width:100%;}.kb-image3999_732440-34 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3999_732440-34\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"410\" src=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-genuine-merino-1024x410.png\" alt=\"\" class=\"kb-img wp-image-4853\" srcset=\"https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-genuine-merino-1024x410.png 1024w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-genuine-merino-300x120.png 300w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-genuine-merino-768x307.png 768w, https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/08\/partner-genuine-merino.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3999_f360d0-2d, .wp-block-kadence-advancedheading.kt-adv-heading3999_f360d0-2d[data-kb-block=\"kb-adv-heading3999_f360d0-2d\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:24px;font-weight:400;font-style:normal;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;}.wp-block-kadence-advancedheading.kt-adv-heading3999_f360d0-2d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_f360d0-2d[data-kb-block=\"kb-adv-heading3999_f360d0-2d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading3999_f360d0-2d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_f360d0-2d\">Lujo natural y rendimiento excepcional<\/h3>\n\n\n<style>#kt-modal3999_8664f1-0f .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:var(--global-palette6, #718096);border-color:var(--global-palette6, #718096);border-radius:4px;font-size:12px;line-height:1.2;letter-spacing:2px;border-width:1px 1px 1px 1px;padding:8px 28px 8px 28px;margin:0px 0px 0px 0px;}#kt-modal3999_8664f1-0f .kt-blocks-modal-link:hover, #kt-modal3999_8664f1-0f .kt-blocks-modal-link:focus{color:#ffffff;background:#444444;border-color:#444444;}#kt-modal3999_8664f1-0f .kt-modal-overlay, #kt-target-modal3999_8664f1-0f .kt-modal-overlay, .kb-modal-content3999_8664f1-0f .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal3999_8664f1-0f .kt-modal-overlay, #kt-target-modal3999_8664f1-0f .kt-modal-overlay, .kb-modal-content3999_8664f1-0f .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal3999_8664f1-0f .kt-modal-container, #kt-target-modal3999_8664f1-0f .kt-modal-container, .kb-modal-content3999_8664f1-0f .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal3999_8664f1-0f .kt-modal-container, #kt-target-modal3999_8664f1-0f .kt-modal-container, .kb-modal-content3999_8664f1-0f .kt-modal-container{padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal3999_8664f1-0f .kt-modal-container, #kt-target-modal3999_8664f1-0f .kt-modal-container, .kb-modal-content3999_8664f1-0f .kt-modal-container{background:#ffffff;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_8664f1-0f .kt-modal-close svg, #kt-target-modal3999_8664f1-0f .kt-modal-close svg, .kb-modal-content3999_8664f1-0f .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal3999_8664f1-0f .kt-modal-container, #kt-target-modal3999_8664f1-0f .kt-modal-container, .kb-modal-content3999_8664f1-0f .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal3999_8664f1-0f .kt-modal-close svg, #kt-target-modal3999_8664f1-0f .kt-modal-close svg, .kb-modal-content3999_8664f1-0f .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal3999_8664f1-0f .kt-modal-container, #kt-target-modal3999_8664f1-0f .kt-modal-container, .kb-modal-content3999_8664f1-0f .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal3999_8664f1-0f .kt-modal-close svg, #kt-target-modal3999_8664f1-0f .kt-modal-close svg, .kb-modal-content3999_8664f1-0f .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center\" id=\"kt-modal3999_8664f1-0f\"><div id=\"kt-target-modal3999_8664f1-0f\" class=\"kb-modal-content3999_8664f1-0f kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal3999_8664f1-0f-content\" class=\"kt-modal-content\">\n<p class=\"wp-block-paragraph\">Genuine Merino<sup>\u00ae<\/sup> es una lana de primera calidad que proviene de oveias Merino cuidadosamente seleccionadas. Reconocida por su suavidad superior y propiedades t\u00e9rmicas optimizadas, esta lana destaca en la industria textil por ofrecer una calidad inigualable y un confort insuperable. Se caracteriza por su fibra extrafina, que no solo proporciona un tacto suave, libre de irritaciones, sino que tambi\u00e9n es excepcional en la gesti\u00f3n de la temperatura corporal. Esta lana mantiene la calidez sin sobrecalentar, gracias a su capacidad natural para respirar, haci\u00e9ndola perfecta para cualquier clima y temporada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Genuine Merino<sup>\u00ae<\/sup> es 100% natural, renovable y biodegradable, y proviene de pr\u00e1cticas de crianza que respetan tanto el bienestar animal como el medio ambiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de su suavidad y rendimiento t\u00e9rmico, es altamente resistente y funcional. Es el\u00e1stica, resistente a las arrugas y naturalmente repelente de olores, lo que la convierte en una opci\u00f3n ideal tanto para ropa casual como para prendas t\u00e9cnicas de alto rendimiento. Su capacidad para absorber la humedad asegura un confort duradero, ideal para la vida activa moderna.<\/p>\n<\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal3999_8664f1-0f\"><span class=\"kt-blocks-modal-link-inner\">DESCUBRIR M\u00c1S<\/span><\/button><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3999_fd01f3-93 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_fd01f3-93 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_fd01f3-93 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id3999_fd01f3-93 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_fd01f3-93 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 3fr) minmax(0, 1fr);}.kb-row-layout-id3999_fd01f3-93{background-image:url('https:\/\/ibq.onlinevalles.club\/wp-content\/uploads\/2024\/10\/bg-x-1.png');background-size:cover 100%;background-position:50% 0%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id3999_fd01f3-93 > .kt-row-layout-overlay{opacity:0.30;background-color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kb-row-layout-id3999_fd01f3-93 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3999_fd01f3-93 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 3fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_fd01f3-93 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3999_fd01f3-93 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}.bg-arrows {background-size: auto 100%;    background-position: right center;}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_fd01f3-93 alignnone has-theme-palette9-background-color kt-row-has-bg bg-arrows wp-block-kadence-rowlayout\" id=\"proyectos\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-center-wide kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_1f921f-7b > .kt-inside-inner-col,.kadence-column3999_1f921f-7b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_1f921f-7b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_1f921f-7b > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_1f921f-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_1f921f-7b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_1f921f-7b{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_1f921f-7b > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_1f921f-7b > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_1f921f-7b\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column3999_c9edca-41 > .kt-inside-inner-col,.kadence-column3999_c9edca-41 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_c9edca-41 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_c9edca-41 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_c9edca-41 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_c9edca-41 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_c9edca-41{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_c9edca-41 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_c9edca-41 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_c9edca-41\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3999_87fd5f-8f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_87fd5f-8f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_87fd5f-8f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_87fd5f-8f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_87fd5f-8f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_87fd5f-8f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_87fd5f-8f alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3999_fa9838-eb > .kt-inside-inner-col,.kadence-column3999_fa9838-eb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_fa9838-eb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_fa9838-eb > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_fa9838-eb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_fa9838-eb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_fa9838-eb{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_fa9838-eb > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_fa9838-eb > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_fa9838-eb\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3999_c76ddd-e6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_c76ddd-e6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_c76ddd-e6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_c76ddd-e6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3999_c76ddd-e6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_c76ddd-e6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_c76ddd-e6 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3999_832d17-3c > .kt-inside-inner-col,.kadence-column3999_832d17-3c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_832d17-3c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_832d17-3c > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_832d17-3c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_832d17-3c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_832d17-3c{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_832d17-3c > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_832d17-3c > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_832d17-3c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3999_4df364-7b, .wp-block-kadence-advancedheading.kt-adv-heading3999_4df364-7b[data-kb-block=\"kb-adv-heading3999_4df364-7b\"]{font-style:normal;font-family:var( --global-heading-font-family, inherit );text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading3999_4df364-7b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_4df364-7b[data-kb-block=\"kb-adv-heading3999_4df364-7b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading3999_4df364-7b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_4df364-7b\"><strong>Soluciones a medida para necesidades espec\u00edficas<\/strong><\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3999_a5bae1-c7, .wp-block-kadence-advancedheading.kt-adv-heading3999_a5bae1-c7[data-kb-block=\"kb-adv-heading3999_a5bae1-c7\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-weight:400;font-style:normal;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;}.wp-block-kadence-advancedheading.kt-adv-heading3999_a5bae1-c7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3999_a5bae1-c7[data-kb-block=\"kb-adv-heading3999_a5bae1-c7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h3 class=\"kt-adv-heading3999_a5bae1-c7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3999_a5bae1-c7\"><strong>En IBQ Textiles, nos especializamos en dise\u00f1ar y producir proyectos a medida, creando tejidos personalizados que se alinean perfectamente con los requisitos \u00fanicos de cada cliente.<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si est\u00e1s listo para dar vida a tus ideas, estamos aqu\u00ed para ayudarte. S\u00f3lo tienes que rellenar nuestro detallado formulario de contacto para compartir las especificaciones y requisitos de su proyecto. Nuestro equipo de expertos se pondr\u00e1 en contacto contigo lo antes posible para hablar de tu visi\u00f3n y estudiar c\u00f3mo podemos hacerla realidad. \u00a1Creemos juntos algo extraordinario!<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns3999_6ce361-26, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns3999_6ce361-26, .wp-block-kadence-advancedbtn.kb-btns3999_6ce361-26, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns3999_6ce361-26{margin-top:var(--global-kb-spacing-xxl, 5rem);margin-bottom:0px;}.wp-block-kadence-advancedbtn.kb-btns3999_6ce361-26{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns3999_6ce361-26 .kt-button{font-weight:normal;font-style:normal;}.kt-btns3999_6ce361-26 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns3999_6ce361-26 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns3999_6ce361-26 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3999_6ce361-26 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns3999_6ce361-26 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns3999_6ce361-26 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns3999_6ce361-26 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3999_6ce361-26\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3999_49fef8-91.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3999_49fef8-91.kb-button{color:var(--global-palette3, #1A202C);background:var(--global-palette9, #ffffff);font-size:16px;font-family:NeueHelveticaPro75Bold, Helvetica, Arial;font-weight:400;text-transform:uppercase;border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:4px;border-bottom-left-radius:4px;border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);padding-top:8px;padding-right:30px;padding-bottom:8px;padding-left:30px;margin-bottom:20px;}.wp-block-kadence-advancedbtn .kb-btn3999_49fef8-91.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3999_49fef8-91.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom-color:var(--global-palette1, #3182CE);border-bottom-style:solid;border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3999_49fef8-91.kb-button{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn3999_49fef8-91.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3999_49fef8-91.kb-button:focus{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom-color:var(--global-palette1, #3182CE);border-bottom-style:solid;border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}}@media all and (max-width: 1024px){.kb-btn3999_49fef8-91.kb-button .kb-svg-icon-wrap{display:block;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn3999_49fef8-91.kb-button{border-top:1px solid var(--global-palette3, #1A202C);border-right:1px solid var(--global-palette3, #1A202C);border-bottom:1px solid var(--global-palette3, #1A202C);border-left:1px solid var(--global-palette3, #1A202C);}.wp-block-kadence-advancedbtn .kb-btn3999_49fef8-91.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn3999_49fef8-91.kb-button:focus{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom-color:var(--global-palette1, #3182CE);border-bottom-style:solid;border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn3999_49fef8-91 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/ibq.onlinevalles.club\/contacto\"><span class=\"kt-btn-inner-text\">Completa el formulario<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3999_8d4fd0-ec > .kt-inside-inner-col,.kadence-column3999_8d4fd0-ec > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_8d4fd0-ec > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_8d4fd0-ec > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_8d4fd0-ec > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_8d4fd0-ec > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_8d4fd0-ec{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_8d4fd0-ec > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_8d4fd0-ec > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_8d4fd0-ec\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3999_6661ee-97{margin-top:0px;}.kb-row-layout-id3999_6661ee-97 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3999_6661ee-97 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3999_6661ee-97 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1490px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-sm, 1.5rem);min-height:90px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3999_6661ee-97 > .kt-row-layout-overlay{opacity:1;background:linear-gradient(180deg,var(--global-palette9) 0%,rgba(255,255,255,0) 100%);}@media all and (max-width: 1024px){.kb-row-layout-id3999_6661ee-97 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3999_6661ee-97 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3999_6661ee-97 alignnone has-theme-palette9-background-color kt-row-has-bg cuadricula-b-- wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3999_9d7cfc-7b > .kt-inside-inner-col,.kadence-column3999_9d7cfc-7b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3999_9d7cfc-7b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3999_9d7cfc-7b > .kt-inside-inner-col{flex-direction:column;}.kadence-column3999_9d7cfc-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3999_9d7cfc-7b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3999_9d7cfc-7b{position:relative;}@media all and (max-width: 1024px){.kadence-column3999_9d7cfc-7b > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column3999_9d7cfc-7b > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3999_9d7cfc-7b\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Fabricado para la seguridad, dise\u00f1ado para la excelencia En IBQ Textiles tenemos la capacidad \u00fanica de controlar todo el proceso de fabricaci\u00f3n, desde la selecci\u00f3n del hilo y el tejido hasta la aplicaci\u00f3n de acabados industriales avanzados. Este enfoque totalmente integrado nos permite innovar en cada fase de la producci\u00f3n, aprovechando nuestras propias instalaciones de&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"disable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"class_list":["post-3999","page","type-page","status-publish","hentry"],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"eloi","author_link":"https:\/\/ibq.onlinevalles.club\/en\/author\/eloi\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/ibq.onlinevalles.club\/en\/wp-json\/wp\/v2\/pages\/3999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibq.onlinevalles.club\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ibq.onlinevalles.club\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ibq.onlinevalles.club\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ibq.onlinevalles.club\/en\/wp-json\/wp\/v2\/comments?post=3999"}],"version-history":[{"count":9,"href":"https:\/\/ibq.onlinevalles.club\/en\/wp-json\/wp\/v2\/pages\/3999\/revisions"}],"predecessor-version":[{"id":6849,"href":"https:\/\/ibq.onlinevalles.club\/en\/wp-json\/wp\/v2\/pages\/3999\/revisions\/6849"}],"wp:attachment":[{"href":"https:\/\/ibq.onlinevalles.club\/en\/wp-json\/wp\/v2\/media?parent=3999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}